{"id":30582,"date":"2024-12-29T07:48:53","date_gmt":"2024-12-29T06:48:53","guid":{"rendered":"https:\/\/www.investglass.com\/?p=30582"},"modified":"2026-02-04T13:10:03","modified_gmt":"2026-02-04T12:10:03","slug":"inbound-vs-outbound-marketing-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/pt\/inbound-vs-outbound-marketing-what-you-need-to-know\/","title":{"rendered":"Inbound vs. Outbound marketing: O que voc\u00ea precisa saber?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 ouviu falar em inbound marketing? Como propriet\u00e1rio de uma empresa, voc\u00ea provavelmente est\u00e1 sempre procurando maneiras de aprimorar seus esfor\u00e7os de marketing. Inbound e outbound <a href=\"https:\/\/www.investglass.com\/pt\/6-bank-marketing-strategies-to-move-you-past-the-competition-in-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">estrat\u00e9gias de marketing <\/a>pode ajud\u00e1-lo a aumentar sua base de clientes e gerar mais receita. Mas qual \u00e9 a diferen\u00e7a entre inbound e outbound marketing? O artigo a seguir discutir\u00e1 as duas abordagens diferentes, como elas funcionam e quando \u00e9 melhor usar cada uma delas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-inbound-marketing\"><span class=\"ez-toc-section\" id=\"Inbound_marketing\"><\/span>Marketing de entrada<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Marketing de entrada \u00e9 o processo de ajudar potenciais clientes a encontrar sua empresa. Isso acontece frequentemente antes mesmo que o cliente esteja pronto para fazer uma compra, mas o contato precoce pode se transformar em prefer\u00eancia de marca e, finalmente, em leads e receita. As estrat\u00e9gias de marketing de entrada envolvem a utiliza\u00e7\u00e3o de muitas formas de marketing de atra\u00e7\u00e3o, como conte\u00fado online, posts de blog, eventos, otimiza\u00e7\u00e3o para mecanismos de busca (SEO), m\u00eddias sociais e esfor\u00e7os de marketing digital. Uma campanha de marketing de entrada bem-sucedida deve ser capaz de criar reconhecimento de marca e atrair novos neg\u00f3cios de forma eficaz. Os esfor\u00e7os de marketing de entrada n\u00e3o devem focar apenas em um canal, mas, em geral, ter uma abordagem multicanal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/02\/IG-email-marketing-1.png\" alt=\"Redator de e-mail com IA da InvestGlass\" class=\"wp-image-44102\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/02\/IG-email-marketing-1.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/02\/IG-email-marketing-1-300x200.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Redator de e-mail com IA da InvestGlass<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-outbound-marketing\"><span class=\"ez-toc-section\" id=\"Outbound_marketing\"><\/span>Marketing de sa\u00edda<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O marketing de sa\u00edda envolve o contato proativo com os consumidores para despertar o interesse deles em um produto, com a esperan\u00e7a de conseguir converter alguns dos clientes em potencial. As t\u00e1ticas de outbound marketing envolvem t\u00e9cnicas mais agressivas, como an\u00fancios em revistas, <a href=\"https:\/\/www.investglass.com\/pt\/how-to-create-a-successful-email-marketing-strategy-in-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">mala direta<\/a>, A t\u00e1tica de outbound \u00e9 mais parecida com os esfor\u00e7os de marketing tradicional, com outdoors, TV e, em geral, com um funil de vendas mais passivo e menos personalizado. As t\u00e1ticas de sa\u00edda s\u00e3o mais semelhantes aos esfor\u00e7os de marketing tradicional, pois voc\u00ea pode ver resultados mais imediatos. Por exemplo, quando voc\u00ea aborda um cliente com um an\u00fancio na TV, a abordagem \u00e9 mais direta e o cliente gostar\u00e1 ou n\u00e3o do an\u00fancio e clicar\u00e1 para comprar seu produto.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-inbound-and-outbound-marketing-key-differences\"><span class=\"ez-toc-section\" id=\"Inbound_and_outbound_marketing_Key_differences\"><\/span>Inbound e outbound marketing: Principais diferen\u00e7as<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 muitas diferen\u00e7as entre o inbound e o outbound marketing. A primeira grande diferen\u00e7a entre o inbound marketing e o outbound marketing \u00e9 como eles encontram os clientes potenciais. O inbound marketing se concentra em atrair tr\u00e1fego e leads para o seu site fornecendo informa\u00e7\u00f5es, conte\u00fado ou servi\u00e7os valiosos que sejam altamente relevantes para as necessidades deles. O outbound marketing depende mais de m\u00e9todos de publicidade paga, como an\u00fancios em mecanismos de pesquisa (SEM) e an\u00fancios em m\u00eddias sociais. O outbound marketing envolve entrar em contato com os consumidores de forma proativa para que eles se interessem por um produto. Por outro lado, uma estrat\u00e9gia de inbound marketing se concentra na cria\u00e7\u00e3o e distribui\u00e7\u00e3o de conte\u00fado que atrai as pessoas para o seu site. Em geral, o marketing de sa\u00edda tem uma abordagem mais agressiva e abrangente, com a expectativa de que pelo menos algumas pessoas sejam convertidas. O inbound marketing geralmente \u00e9 mais sutil e se concentra em convencer um grupo espec\u00edfico de pessoas a fazer uma compra ao longo do tempo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A \u00fanica pergunta que voc\u00ea precisa fazer a si mesmo antes de investir em uma nova estrat\u00e9gia de marketing \u00e9 \u201cO que acontecer\u00e1 se eu n\u00e3o mudar?\u201d. Isso pode parecer assustador, mas o futuro de sua empresa pode depender disso. Se voc\u00ea quiser ajuda para atualizar seu plano de marketing digital atual com tecnologias emergentes que certamente mudar\u00e3o o jogo em 2021, podemos come\u00e7ar agora! InvestGlass <a href=\"https:\/\/www.investglass.com\/pt\/ferramentas-de-marketing\/\" target=\"_blank\" rel=\"noreferrer noopener\">automa\u00e7\u00e3o de marketing<\/a> As ferramentas de solu\u00e7\u00e3o e comunica\u00e7\u00e3o podem ajudar sua empresa a obter uma vantagem competitiva em rela\u00e7\u00e3o aos concorrentes e aumentar as vendas. <a href=\"https:\/\/www.investglass.com\/pt\/comece-a-usar-gratuitamente\/\" target=\"_blank\" rel=\"noreferrer noopener\">Entre em contato conosco<\/a> hoje para ver como podemos fazer uma parceria!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"FAQ_InvestGlass_Email_and_Marketing_Tools\"><\/span>PERGUNTAS FREQUENTES: Ferramentas de e-mail e marketing da InvestGlass<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_What_marketing_automation_features_does_InvestGlass_provide\"><\/span>1. Quais s\u00e3o os recursos de automa\u00e7\u00e3o de marketing oferecidos pela InvestGlass?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A InvestGlass oferece automa\u00e7\u00e3o para tarefas repetitivas de marketing, tais como a nutri\u00e7\u00e3o de leads, a entrega de conte\u00fado e o acompanhamento. Isso ajuda as equipes a economizar tempo e a aumentar a efici\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Can_InvestGlass_handle_email_campaigns\"><\/span>2. A InvestGlass pode gerenciar campanhas de e-mail?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sim, a InvestGlass oferece suporte a campanhas de e-mail personalizadas com modelos personalizados, regras de automa\u00e7\u00e3o e ferramentas de rastreamento para medir o envolvimento, como taxas de abertura e de cliques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Does_InvestGlass_support_multi-channel_communication\"><\/span>3. O InvestGlass oferece suporte \u00e0 comunica\u00e7\u00e3o multicanal?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O InvestGlass permite o alcance por e-mail, SMS e WhatsApp, facilitando o envolvimento de clientes potenciais e clientes nos canais que eles mais usam.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_How_does_InvestGlass_help_with_lead_generation\"><\/span>4. Como a InvestGlass ajuda na gera\u00e7\u00e3o de leads?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os leads podem ser capturados automaticamente de sites, e-mails e m\u00eddias sociais. O InvestGlass os leva para o CRM sem a necessidade de entrada manual, simplificando o processo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_What_is_lead_scoring_and_how_does_InvestGlass_use_it\"><\/span>5. O que \u00e9 pontua\u00e7\u00e3o de leads e como a InvestGlass a utiliza?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A pontua\u00e7\u00e3o de leads \u00e9 o processo de classifica\u00e7\u00e3o de clientes potenciais com base em sua probabilidade de convers\u00e3o. A InvestGlass aplica modelos de pontua\u00e7\u00e3o personalizados para ajudar as equipes a priorizar os leads de alto valor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Can_InvestGlass_segment_customer_lists\"><\/span>6. A InvestGlass pode segmentar as listas de clientes?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sim, a InvestGlass oferece segmenta\u00e7\u00e3o din\u00e2mica com base em dados demogr\u00e1ficos, comportamento e envolvimento. Isso garante que as campanhas sejam direcionadas e relevantes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_How_does_InvestGlass_support_campaign_tracking\"><\/span>7. Como a InvestGlass oferece suporte ao rastreamento de campanhas?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O desempenho da campanha \u00e9 monitorado por meio de pain\u00e9is de an\u00e1lise, permitindo que as empresas vejam as taxas de abertura, o comportamento dos cliques e as convers\u00f5es para refinar as estrat\u00e9gias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"8_Does_InvestGlass_integrate_marketing_with_CRM_data\"><\/span>8. A InvestGlass integra o marketing com os dados de CRM?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Todas as a\u00e7\u00f5es de marketing s\u00e3o vinculadas aos registros de CRM. Essa integra\u00e7\u00e3o garante que as equipes de vendas, servi\u00e7os e marketing vejam a jornada completa do cliente em um s\u00f3 lugar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"9_What_workflow_automation_options_are_available\"><\/span>9. Quais op\u00e7\u00f5es de automa\u00e7\u00e3o de fluxo de trabalho est\u00e3o dispon\u00edveis?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A InvestGlass pode automatizar as aprova\u00e7\u00f5es, atribuir tarefas e acionar notifica\u00e7\u00f5es quando os leads se envolvem. Isso cria uma conex\u00e3o perfeita entre as campanhas de marketing e os pipelines de vendas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"10_Where_can_InvestGlass_be_hosted\"><\/span>10. Onde o InvestGlass pode ser hospedado?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O InvestGlass pode ser hospedado na infraestrutura segura da nuvem su\u00ed\u00e7a ou no local, oferecendo \u00e0s empresas controle total da soberania dos dados e conformidade com as regulamenta\u00e7\u00f5es locais.<\/p>","protected":false},"excerpt":{"rendered":"<p>Have you heard about inbound marketing? As a business owner, you are probably always looking for ways to improve your marketing efforts. Inbound and outbound marketing strategies can help you grow your customer base and generate more revenue. But what is the difference between inbound and outbound marketing? The following article will discuss the two [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[19,35,43,105,39,44,104,48],"class_list":["post-30582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-crm","tag-crm-for-banking","tag-email-marketing","tag-financial-services-marketing","tag-marketing","tag-marketing-automation","tag-marketing-techniques","tag-sales-automation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Inbound vs Outbound Marketing: Key Differences Explained | InvestGlass<\/title>\n<meta name=\"description\" content=\"Explore the key differences between inbound vs outbound marketing and how each can boost your business growth effectively.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/pt\/inbound-vs-outbound-marketing-o-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inbound vs Outbound marketing: What you need to Know?\" \/>\n<meta property=\"og:description\" content=\"Have you heard about inbound marketing? As a business owner, you are probably always looking for ways to improve your marketing efforts. Inbound and\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/pt\/inbound-vs-outbound-marketing-o-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-29T06:48:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T12:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inbound vs Outbound Marketing: Principais diferen\u00e7as explicadas | InvestGlass","description":"Explore as principais diferen\u00e7as entre o inbound e o outbound marketing e como cada um deles pode impulsionar o crescimento de sua empresa de forma eficaz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/pt\/inbound-vs-outbound-marketing-o-que-voce-precisa-saber\/","og_locale":"pt_BR","og_type":"article","og_title":"Inbound vs Outbound marketing: What you need to Know?","og_description":"Have you heard about inbound marketing? As a business owner, you are probably always looking for ways to improve your marketing efforts. Inbound and","og_url":"https:\/\/www.investglass.com\/pt\/inbound-vs-outbound-marketing-o-que-voce-precisa-saber\/","og_site_name":"InvestGlass","article_published_time":"2024-12-29T06:48:53+00:00","article_modified_time":"2026-02-04T12:10:03+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Escrito por":"InvestGlass","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"Inbound vs Outbound marketing: What you need to Know?","datePublished":"2024-12-29T06:48:53+00:00","dateModified":"2026-02-04T12:10:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/"},"wordCount":826,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg","keywords":["CRM","CRM for banking","email marketing","financial services marketing","marketing","marketing automation","marketing techniques","sales automation"],"articleSection":["Article"],"inLanguage":"pt-BR","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/pt\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/","url":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/","name":"Inbound vs Outbound Marketing: Principais diferen\u00e7as explicadas | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg","datePublished":"2024-12-29T06:48:53+00:00","dateModified":"2026-02-04T12:10:03+00:00","description":"Explore as principais diferen\u00e7as entre o inbound e o outbound marketing e como cada um deles pode impulsionar o crescimento de sua empresa de forma eficaz.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/yktk2qaivhi.jpg","width":1600,"height":1067,"caption":"white printing paper with Marketing Strategy text"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"Inbound vs Outbound marketing: What you need to Know?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"O CRM Soberano da Su\u00ed\u00e7a","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/pt\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.investglass.com\/inbound-vs-outbound-marketing-what-you-need-to-know\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts\/30582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/comments?post=30582"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts\/30582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/media\/30583"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/media?parent=30582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/categories?post=30582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/tags?post=30582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}