{"id":29144,"date":"2021-05-16T22:24:23","date_gmt":"2021-05-16T20:24:23","guid":{"rendered":"https:\/\/www.investglass.com\/?p=29144"},"modified":"2024-07-18T11:30:23","modified_gmt":"2024-07-18T09:30:23","slug":"o-que-e-o-mercado-de-titulos","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/pt\/what-is-the-bond-market\/","title":{"rendered":"O que \u00e9 o mercado de t\u00edtulos?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Os t\u00edtulos de renda fixa s\u00e3o um tipo de t\u00edtulo de renda fixa emitido por empresas, governos e entidades supranacionais para captar recursos. Os t\u00edtulos de renda fixa podem ser considerados como empr\u00e9stimos feitos por investidores que emprestam dinheiro ao emissor em troca de uma promessa do emissor de pagar o empr\u00e9stimo em uma data futura, juntamente com o pagamento de juros em intervalos regulares. O prazo do t\u00edtulo determinar\u00e1 quanto tempo levar\u00e1 para voc\u00ea receber seu investimento de volta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vimos fintechs interessantes abordando esse t\u00f3pico, mas o mercado ser\u00e1 reformulado com as NFTs. <a href=\"https:\/\/www.investglass.com\/pt\/crm-para-bancos-corporativos\/\">instrumentos financeiros<\/a> mas n\u00e3o s\u00e3o um t\u00edtulo. N\u00e3o \u00e9 poss\u00edvel negoci\u00e1-los como se fossem t\u00edtulos e, em vez disso, voc\u00ea compra ou vende os tokens que representam um ativo no blockchain.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-government-bonds\"><span class=\"ez-toc-section\" id=\"What_are_government_bonds\"><\/span>O que s\u00e3o t\u00edtulos p\u00fablicos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os t\u00edtulos p\u00fablicos s\u00e3o um tipo de instrumento emitido por um governo que toma dinheiro emprestado do p\u00fablico. Geralmente, \u00e9 para financiar despesas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-corporate-bonds\"><span class=\"ez-toc-section\" id=\"What_are_corporate_bonds\"><\/span>O que s\u00e3o t\u00edtulos corporativos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os t\u00edtulos corporativos s\u00e3o instrumentos de d\u00edvida usados para empr\u00e9stimos <a href=\"https:\/\/www.investglass.com\/pt\/portal-do-investidor-do-fundo\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1138\">fundos de investidores<\/a> para financiar as opera\u00e7\u00f5es comerciais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-the-bond-face-value\"><span class=\"ez-toc-section\" id=\"What_is_the_bond_face_value\"><\/span>Qual \u00e9 o valor nominal do t\u00edtulo?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O valor nominal do t\u00edtulo \u00e9 a quantia de dinheiro que a empresa pagar\u00e1 ao investidor no vencimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-bonds-rated\"><span class=\"ez-toc-section\" id=\"What_are_bonds_rated\"><\/span>Qual \u00e9 a classifica\u00e7\u00e3o dos t\u00edtulos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os t\u00edtulos de renda fixa podem receber classifica\u00e7\u00f5es de ag\u00eancias de classifica\u00e7\u00e3o de cr\u00e9dito, que indicam o grau de risco que eles representam como investimentos com rela\u00e7\u00e3o a poss\u00edveis inadimpl\u00eancias ou mudan\u00e7as de valor. As principais ag\u00eancias de classifica\u00e7\u00e3o s\u00e3o a Moody's, a Standard &amp; Poor's (S&amp;P) e a Fitch Ratings. \u00c9 poss\u00edvel comprar seus feeds e adicion\u00e1-los ao InvestGlass por meio de uma API ou de arquivos simples. <a href=\"https:\/\/www.investglass.com\/pt\/investimento-na-esg-como-os-fatores-da-esg-estao-moldando-as-decisoes-de-investimento\/\">Classifica\u00e7\u00e3o ESG<\/a> para esses t\u00edtulos e gerenciar com o InvestGlass PMS a classifica\u00e7\u00e3o ESG m\u00e9dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-do-you-invest-in-bonds\"><span class=\"ez-toc-section\" id=\"How_do_you_invest_in_Bonds\"><\/span>Como voc\u00ea investe em t\u00edtulos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode compr\u00e1-los e vend\u00ea-los por meio de qualquer conta de corretagem com uma plataforma de negocia\u00e7\u00e3o on-line. Voc\u00ea precisar\u00e1 das informa\u00e7\u00f5es de login e senha de sua corretora para acessar o site, onde poder\u00e1 negociar em seu pr\u00f3prio nome, bem como analisar relat\u00f3rios sobre as pr\u00f3ximas ofertas de t\u00edtulos e pesquisar os pre\u00e7os atuais dos t\u00edtulos existentes, entre outros recursos normalmente encontrados na maioria das principais institui\u00e7\u00f5es financeiras, como TD Ameritrade, Fidelity Investments, E*Trade Financial Corporation (Etrade) e Swissquote.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-bond-interest-rates\"><span class=\"ez-toc-section\" id=\"What_are_bond_interest_rates\"><\/span>O que s\u00e3o taxas de juros de t\u00edtulos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As taxas de juros dos t\u00edtulos s\u00e3o chamadas de taxas de cupom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os pre\u00e7os dos t\u00edtulos e as taxas de juros normalmente se movem em dire\u00e7\u00f5es opostas: Quando o pre\u00e7o de um t\u00edtulo aumenta, seu rendimento cai; quando o rendimento aumenta, os pre\u00e7os dos t\u00edtulos caem. Os dois est\u00e3o relacionados porque os t\u00edtulos com cupons mais altos t\u00eam retornos potenciais menores do que aqueles com pagamentos de cupons mais baixos. Os t\u00edtulos com cupons mais altos tendem a vencer em per\u00edodos mais longos, que podem se estender por d\u00e9cadas ou at\u00e9 s\u00e9culos, enquanto os t\u00edtulos com taxas mais baixas ser\u00e3o pagos mais cedo e ter\u00e3o dura\u00e7\u00f5es mais curtas. Entretanto, se voc\u00ea preferir investir em t\u00edtulos de governos ou empresas que talvez n\u00e3o ofere\u00e7am fluxos de renda garantidos como os dividendos das a\u00e7\u00f5es, mas ainda assim quiser diversificar em equities (a\u00e7\u00f5es), n\u00e3o h\u00e1 op\u00e7\u00e3o melhor do que os t\u00edtulos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-the-bond-market-price\"><span class=\"ez-toc-section\" id=\"What_is_the_bond_market_price\"><\/span>Qual \u00e9 o pre\u00e7o do mercado de t\u00edtulos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00ednculo <a href=\"https:\/\/www.investglass.com\/pt\/ia-na-analise-do-mercado-imobiliario-o-uso-da-ia-na-analise-dos-mercados-imobiliarios-e-seu-impacto-na-inflacao-dos-precos-imobiliarios\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1939\">pre\u00e7o de mercado<\/a> \u00e9 o pre\u00e7o pelo qual os traders comprar\u00e3o ou vender\u00e3o t\u00edtulos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O rendimento de um t\u00edtulo \u00e9 o pagamento anual do cupom dividido pelo pre\u00e7o de compra, expresso como uma taxa de juros. Por exemplo, se voc\u00ea investir $1000 em um t\u00edtulo do Tesouro de 20 anos que paga 12% por ano, seu retorno ser\u00e1 de 0,12 * $1000 = 120 d\u00f3lares por ano durante 20 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea deve entender o que \u00e9 o rendimento at\u00e9 a data de vencimento de um t\u00edtulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 a taxa de juros que pode ser obtida em um investimento se ele for mantido at\u00e9 o vencimento e pago no final, em vez de ser resgatado antecipadamente, como pode ocorrer com t\u00edtulos em ofertas n\u00e3o garantidas ou a\u00e7\u00f5es vendidas antes da conclus\u00e3o do per\u00edodo de aquisi\u00e7\u00e3o de direitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/www.investglass.com\/pt\/o-efeito-da-ia-sobre-os-mercados-financeiros-e-seu-impacto-indireto-sobre-a-inflacao\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1862\">impacto da infla\u00e7\u00e3o<\/a> O impacto do risco de cr\u00e9dito \u00e9 que ele pode reduzir o rendimento do t\u00edtulo at\u00e9 o vencimento. O impacto do risco de cr\u00e9dito \u00e9 que ele aumentar\u00e1 a taxa de juros que o detentor do t\u00edtulo deve pagar por determinados t\u00edtulos. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-junk-bonds\"><span class=\"ez-toc-section\" id=\"What_are_junk_bonds\"><\/span>O que s\u00e3o junk bonds?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os junk bonds s\u00e3o uma forma comum de t\u00edtulos de renda fixa em que a qualidade est\u00e1 abaixo da dos t\u00edtulos com grau de investimento. Em outras palavras, alto risco e baixa prote\u00e7\u00e3o ao investidor para um retorno maior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-is-it-difficult-to-trade-bonds\"><span class=\"ez-toc-section\" id=\"Is_it_difficult_to_trade_bonds\"><\/span>\u00c9 dif\u00edcil negociar t\u00edtulos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A negocia\u00e7\u00e3o de t\u00edtulos \u00e9 um pouco mais dif\u00edcil do que a negocia\u00e7\u00e3o de a\u00e7\u00f5es porque o bilhete \u00e9 maior do que o das a\u00e7\u00f5es. Entretanto, voc\u00ea tamb\u00e9m pode investir por meio de ETFs e ETNs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os t\u00edtulos podem ser renderizados no InvestGlass <a href=\"https:\/\/www.investglass.com\/pt\/carteira-financeira\/\">solu\u00e7\u00e3o de gerenciamento de portf\u00f3lio<\/a> para refletir a situa\u00e7\u00e3o do fluxo de caixa e analisar o risco.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bonds are a type of fixed-income security that is issued by corporations, governments and supranational entities to raise money. Bonds can be thought of as loans made by investors who lend the issuer money in exchange for a promise from the issuer to repay the loan at some future date, along with interest payments at [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[511],"class_list":["post-29144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-what-is-the-bond-market"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>What is The Bond Market? | InvestGlass<\/title>\n<meta name=\"description\" content=\"Bonds are a type of fixed-income security that is issued by corporations, governments and supranational entities to raise money. Bonds can be thought of\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/pt\/o-que-e-o-mercado-de-titulos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is The Bond Market?\" \/>\n<meta property=\"og:description\" content=\"Bonds are a type of fixed-income security that is issued by corporations, governments and supranational entities to raise money. Bonds can be thought of\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/pt\/o-que-e-o-mercado-de-titulos\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-16T20:24:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T09:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1065\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O que \u00e9 o mercado de t\u00edtulos? | InvestGlass","description":"Os t\u00edtulos de renda fixa s\u00e3o um tipo de t\u00edtulo de renda fixa emitido por empresas, governos e entidades supranacionais para arrecadar dinheiro. Os t\u00edtulos podem ser considerados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/pt\/o-que-e-o-mercado-de-titulos\/","og_locale":"pt_BR","og_type":"article","og_title":"What is The Bond Market?","og_description":"Bonds are a type of fixed-income security that is issued by corporations, governments and supranational entities to raise money. Bonds can be thought of","og_url":"https:\/\/www.investglass.com\/pt\/o-que-e-o-mercado-de-titulos\/","og_site_name":"InvestGlass","article_published_time":"2021-05-16T20:24:23+00:00","article_modified_time":"2024-07-18T09:30:23+00:00","og_image":[{"width":1600,"height":1065,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Escrito por":"InvestGlass","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"What is The Bond Market?","datePublished":"2021-05-16T20:24:23+00:00","dateModified":"2024-07-18T09:30:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/"},"wordCount":745,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg","keywords":["what is the bond market"],"articleSection":["Article"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/pt\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/","url":"https:\/\/www.investglass.com\/what-is-the-bond-market\/","name":"O que \u00e9 o mercado de t\u00edtulos? | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg","datePublished":"2021-05-16T20:24:23+00:00","dateModified":"2024-07-18T09:30:23+00:00","description":"Os t\u00edtulos de renda fixa s\u00e3o um tipo de t\u00edtulo de renda fixa emitido por empresas, governos e entidades supranacionais para arrecadar dinheiro. Os t\u00edtulos podem ser considerados","breadcrumb":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/what-is-the-bond-market\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/t1oalcbuyrc.jpg","width":1600,"height":1065,"caption":"grey metal chain on white background"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"What is The Bond Market?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"O CRM Soberano da Su\u00ed\u00e7a","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/pt\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.investglass.com\/what-is-the-bond-market\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts\/29144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/comments?post=29144"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/posts\/29144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/media\/29145"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/media?parent=29144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/categories?post=29144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/pt\/wp-json\/wp\/v2\/tags?post=29144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}