{"id":29038,"date":"2021-05-16T18:04:05","date_gmt":"2021-05-16T16:04:05","guid":{"rendered":"https:\/\/www.investglass.com\/?p=29038"},"modified":"2025-11-06T20:02:57","modified_gmt":"2025-11-06T19:02:57","slug":"come-digitalizzare-in-modo-efficiente-il-processo-di-onboarding","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/it\/how-to-efficiently-digitalize-your-onboarding-process\/","title":{"rendered":"Come digitalizzare in modo efficiente il processo di onboarding?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Tutti i settori utilizzano ampiamente il termine \u201cDigital onboarding\u201d, ma il suo significato varia. Nei servizi bancari e finanziari, per onboarding digitale si intende la creazione di conti bancari o di registri simili online. Per quanto riguarda il CRM, il significato si avvicina a quello di un'azienda che utilizza il sistema CRM e i suoi strumenti di onboarding. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dal 2016 la FINMA ha abilitato l'onboarding dei clienti in forma puramente digitale. Le soluzioni di verifica dell'identit\u00e0 hanno reso il processo di onboarding sicuro e l'identit\u00e0 del cliente verificabile tramite la tecnologia di machine learning.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"geodir-embed-container\"><iframe loading=\"lazy\" title=\"Che cos&#039;\u00e8 la digitalizzazione dei documenti?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/it\/onboarding-digitale\/\"   title=\"Onboarding digitale\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"116\">Onboarding digitale<\/a> in un'ottica di medio-lungo termine superer\u00e0 i moduli cartacei e la raccolta tradizionale dei dati KYC. Questa digitalizzazione consente di ridurre la forza lavoro e i costi per le aziende e le societ\u00e0, soprattutto nel settore bancario e nei flussi di apertura dei conti bancari. Una volta a bordo, i clienti sono facilmente gestibili e diventano utenti dell'interfaccia CRM. Possiamo condividere la fornitura di un portale per i clienti, la bonifica KYC o le necessit\u00e0 supplementari di onboarding come il caricamento di file (documenti d'identit\u00e0, prove di indirizzo e cos\u00ec via) tramite la piattaforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizzando il CRM, i dipendenti possono personalizzare la soluzione di onboarding e influenzare il percorso di onboarding. L'onboarding dei dipendenti pu\u00f2 anche migliorare le capacit\u00e0 dell'azienda, consentendo la flessibilit\u00e0 del team delle risorse umane con una gestione efficiente dei talenti al momento dell'assunzione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-digital-onboarding-financial-services-with-investglass\"><span class=\"ez-toc-section\" id=\"Digital_Onboarding_%E2%80%93_Financial_Services_with_InvestGlass\"><\/span>Onboarding digitale - Servizi finanziari con InvestGlass<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">InvestGlass offre una soluzione CRM all-in-one che include un processo di onboarding completo. I nostri clienti possono scegliere tra l'onboarding completamente digitale, l'onboarding completamente cartaceo o un mix di entrambi, anche se il mantenimento della carta aumenta il carico di lavoro manuale. L'onboarding digitale pu\u00f2 essere suddiviso in tre fasi principali. In primo luogo, il cliente deve compilare uno o pi\u00f9 moduli per inserire correttamente le proprie informazioni nella macchina. In secondo luogo, l'avvio dei processi di approvazione e di verifica dell'identit\u00e0. Infine, la bonifica KYC pu\u00f2 essere effettuata in una fase successiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'invito alla raccolta dei dati pu\u00f2 assumere diverse forme a seconda dell'esperienza utente desiderata. <a href=\"https:\/\/www.investglass.com\/it\/le-cose-da-sapere-prima-di-avviare-la-vostra-banca-digitale\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"447\">Le banche devono digitalizzarsi<\/a> i loro moduli di onboarding che possono poi essere inviati a prospect specifici. \u00c8 possibile inviare questi moduli via e-mail o incorporare semplici moduli di firma nel proprio sito web. A seconda della politica sulla privacy dell'organizzazione, i clienti potenziali potrebbero gi\u00e0 disporre di un portale clienti, nel qual caso i moduli potrebbero essere condivisi direttamente attraverso il portale. I potenziali clienti devono semplicemente compilare le informazioni e i file necessari tramite i moduli e voi riceverete una notifica una volta terminato il loro lavoro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1024x705.png\" alt=\"\" class=\"wp-image-32243\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1024x705.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-300x207.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-768x529.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1536x1058.png 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Strumento di campagna di InvestGlass costruito per le bonifiche KYC e l'onboarding digitale<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L'onboarding digitale mira a semplificare l'adozione da parte di clienti e consumatori, decidendo se accettare o rifiutare un prospect. Le aziende vogliono anche verificare l'identit\u00e0 dei clienti potenziali e controllare i loro nomi nelle liste antiriciclaggio e di allerta. Per verificare gli individui e le persone che compilano i moduli, \u00e8 possibile utilizzare una serie di partner, dai controlli antiriciclaggio alla verifica dell'identit\u00e0 tramite riconoscimento facciale. \u00c8 possibile automatizzare questi controlli o avviarli manualmente, a seconda delle esigenze. Una volta che un potenziale cliente rientra in una categoria, ad esempio a basso rischio, a medio rischio o PEP, \u00e8 possibile avviare (in modo automatico o meno) un'analisi di sicurezza. <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/it\/strumenti-di-vendita\/\" target=\"_blank\" rel=\"noopener\" title=\"processo di approvazione\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"734\">processo di approvazione<\/a>. I processi di approvazione consentono di accettare o rifiutare i clienti in base alle loro risposte, al livello di rischio e cos\u00ec via. Siete voi a stabilire le regole del gioco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una volta accettato un prospect, \u00e8 possibile creare un accesso al portale clienti, avviare comunicazioni, condividere documenti, creare proposte di investimento e utilizzare tutte le funzionalit\u00e0 e i prodotti della soluzione per creare relazioni solide e durature. Ma soprattutto, \u00e8 possibile creare un'offerta di marketing <a href=\"https:\/\/www.investglass.com\/it\/automazione-robotica-dei-processi-rpa-come-puo-trasformare-la-vostra-azienda\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"271\">automatizzare e sviluppare facilmente processi di bonifica KYC<\/a>. Ad esempio, si potrebbe voler impostare un controllo KYC se un utente cambia indirizzo, nazionalit\u00e0 o stato civile. Il controllo KYC consiste nel verificare le informazioni dei clienti. Di solito, \u00e8 tempestiva o in occasione di eventi speciali. Tramite InvestGlass, \u00e8 possibile notificare la bonifica su qualsiasi dispositivo e condividere i moduli di bonifica tramite e-mail o portale clienti. Ovviamente le modalit\u00e0 tradizionali, come le telefonate o gli incontri di persona, sono ancora possibili, ma noi vogliamo passare al digitale!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1024x683.jpg\" alt=\"persona che cammina tenendo in mano una borsa di pelle marrone\" class=\"wp-image-29040\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1024x683.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-300x200.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-768x512.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1536x1024.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-do-not-forget-the-client-is-human\"><span class=\"ez-toc-section\" id=\"Do_not_forget_the_client_is_human\"><\/span>Non dimenticate che il cliente \u00e8 umano!<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Concentriamoci su trucchi e suggerimenti per l'onboarding dei clienti potenziali. Che siate un <a href=\"https:\/\/www.investglass.com\/it\/le-principali-sfide-delladozione-dellai-nel-settore-bancario-e-come-superarle\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2273\">banca sfidante<\/a> o uno gi\u00e0 affermato, potrebbero suscitare il vostro interesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'organizzazione \u00e8 tutto. Quando impostate i moduli e il processo di onboarding, assicuratevi che il flusso di lavoro e ogni fase siano chiari e completi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rimanete semplici e veloci. Non dovreste chiedere a un potenziale cliente di compilare un modulo per pi\u00f9 di 10 minuti.<br>Distribuire l'onboarding. Per mantenere l'impegno del vostro prospect, distribuite il processo in diverse fasi.<br>Stabilite aspettative e obiettivi chiari. Questo vi aiuter\u00e0 a valutare le metriche e la qualit\u00e0 dell'onboarding. In questo modo, potrete massimizzare l'acquisizione dei clienti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ottenere regolarmente un feedback. Attivate il feedback dei vostri clienti e potenziali clienti per migliorare i vostri flussi di lavoro. Adottate l'onboarding digitale e aspettatevi un aumento di 80% dei vostri tassi di fidelizzazione! Tuttavia, monitorate attentamente il vostro processo, poich\u00e9 l'anno scorso 60% di clienti hanno abbandonato l'onboarding digitale per diversi motivi, come la complessit\u00e0, la lunghezza, ecc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.investglass.com\/it\/iniziare-gratuitamente\/\">Iniziamo con la prova gratuita di InvestGlass<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>All sectors widely use the term &#8220;Digital onboarding&#8221;; however, its meaning varies. In banking and financial services, digital onboarding means the creation of banking accounts or similar records online. Focusing on CRM, the meaning is close to one of the businesses using the CRM system and its onboarding tools. Since 2016, FINMA has enabled customer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[45],"class_list":["post-29038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-digital-onboarding"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How to Efficiently Digitalize your Onboarding Process? | InvestGlass<\/title>\n<meta name=\"description\" content=\"Learn how to digitalize your onboarding process to reduce manual work, improve compliance, and deliver a seamless client experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/it\/come-digitalizzare-in-modo-efficiente-il-processo-di-onboarding\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Efficiently Digitalize your Onboarding Process?\" \/>\n<meta property=\"og:description\" content=\"All sectors widely use the term &quot;Digital onboarding&quot;; however, its meaning varies. In banking and financial services, digital onboarding means the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/it\/come-digitalizzare-in-modo-efficiente-il-processo-di-onboarding\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-16T16:04:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"2125\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2021-05-16T16:04:05+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come digitalizzare in modo efficiente il processo di onboarding? | InvestGlass","description":"Scoprite come digitalizzare il vostro processo di onboarding per ridurre il lavoro manuale, migliorare la conformit\u00e0 e offrire un'esperienza di cliente senza soluzione di continuit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/it\/come-digitalizzare-in-modo-efficiente-il-processo-di-onboarding\/","og_locale":"it_IT","og_type":"article","og_title":"How to Efficiently Digitalize your Onboarding Process?","og_description":"All sectors widely use the term \"Digital onboarding\"; however, its meaning varies. In banking and financial services, digital onboarding means the","og_url":"https:\/\/www.investglass.com\/it\/come-digitalizzare-in-modo-efficiente-il-processo-di-onboarding\/","og_site_name":"InvestGlass","article_published_time":"2021-05-16T16:04:05+00:00","article_modified_time":"2025-11-06T19:02:57+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Scritto da":"InvestGlass","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"How to Efficiently Digitalize your Onboarding Process?","datePublished":"2021-05-16T16:04:05+00:00","dateModified":"2025-11-06T19:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"},"wordCount":831,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","keywords":["Digital onboarding"],"articleSection":["Article"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/","url":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/","name":"Come digitalizzare in modo efficiente il processo di onboarding? | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","datePublished":"2021-05-16T16:04:05+00:00","dateModified":"2025-11-06T19:02:57+00:00","description":"Scoprite come digitalizzare il vostro processo di onboarding per ridurre il lavoro manuale, migliorare la conformit\u00e0 e offrire un'esperienza di cliente senza soluzione di continuit\u00e0.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","width":1600,"height":1067,"caption":"person walking holding brown leather bag"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"How to Efficiently Digitalize your Onboarding Process?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"Il sovrano svizzero CRM","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/it\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]},"og_video":"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI","og_video_type":"text\/html","og_video_duration":"2125","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2021-05-16T16:04:05+00:00","ya_ovs_allow_embed":"true"},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/posts\/29038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/comments?post=29038"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/posts\/29038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/media\/29040"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/media?parent=29038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/categories?post=29038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/it\/wp-json\/wp\/v2\/tags?post=29038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}