{"id":34423,"date":"2022-08-27T08:23:10","date_gmt":"2022-08-27T06:23:10","guid":{"rendered":"https:\/\/www.investglass.com\/?p=34423"},"modified":"2025-02-24T09:42:44","modified_gmt":"2025-02-24T08:42:44","slug":"comment-mettre-en-oeuvre-le-fina","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/fr\/how-to-implement-finsa\/","title":{"rendered":"Comment mettre en \u0153uvre le FINSA ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><em><span style=\"text-decoration: underline;\">IL NE S'AGIT PAS D'UN AVIS JURIDIQUE - VEUILLEZ CONSULTER VOTRE PROPRE CONSEILLER JURIDIQUE.<\/span><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis le 1er janvier 2018, la loi sur les services financiers (LSFin) est entr\u00e9e en vigueur en Suisse (le Conseil f\u00e9d\u00e9ral r\u00e8gle les nouveaux d\u00e9tails). Cette nouvelle loi remplace l'ancienne loi sur les banques et r\u00e9git tous les prestataires de services financiers en Suisse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'objectif principal de la FinSA est de prot\u00e9ger les consommateurs en veillant \u00e0 ce que seuls des prestataires qualifi\u00e9s et r\u00e9put\u00e9s offrent des services financiers en Suisse. Pour pouvoir op\u00e9rer en tant que prestataire de services financiers en Suisse, vous devez d\u00e9sormais obtenir une licence aupr\u00e8s de la FINMA, l'autorit\u00e9 de r\u00e9gulation financi\u00e8re suisse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">elon la\u00a0<a href=\"https:\/\/www.finma.ch\/en\/documentation\/legal-basis\/laws-and-ordinances\/finanzdienstleistungen\/?utm_source=chatgpt.com\">FINMA<\/a>, environ\u00a0<strong>2,000 - 2,500<\/strong>\u00a0Les soci\u00e9t\u00e9s financi\u00e8res en Suisse ont \u00e9t\u00e9 touch\u00e9es par la r\u00e9glementation FinSA depuis son entr\u00e9e en vigueur en 2020. \u00c0 partir de 2022, plus de\u00a0<strong>1 500 conseillers financiers<\/strong>\u00a0ont \u00e9t\u00e9 enregistr\u00e9s aupr\u00e8s de l'Agence europ\u00e9enne pour la s\u00e9curit\u00e9 et la sant\u00e9 au travail.\u00a0<strong>Registre des conseillers financiers (Beraterregister)<\/strong>\u00a0pour se conformer aux nouvelles exigences. Les prestataires de services financiers qui g\u00e8rent des actifs d\u00e9passant\u00a0<strong>10 millions de francs suisses<\/strong>\u00a0(environ 11,2 millions USD) doivent obtenir une licence de la FINMA. Le non-respect de la FinSA peut entra\u00eener des sanctions allant jusqu'\u00e0\u00a0<strong>500 000 FRANCS SUISSES<\/strong>\u00a0(environ 560 000 USD). En outre, le r\u00e8glement renforce la protection des investisseurs pour plus de 1,5 million d'euros.\u00a0<strong>4,5 millions d'investisseurs individuels<\/strong>\u00a0en Suisse en assurant une plus grande transparence des produits et services financiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seuls les prestataires qui remplissent des conditions rigoureuses et se conforment \u00e0 des r\u00e8gles et r\u00e9glementations strictes se verront accorder une licence par la FINMA. Qu'est-ce que cela signifie pour les clients et comment InvestGlass <a href=\"https:\/\/www.investglass.com\/fr\/que-font-les-banques-avec-le-chatgpt-et-lautomatisation-des-processus-robotiques-rpa\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1099\">automatiser ce processus bancaire<\/a>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0-1024x576.jpg\" alt=\"\" class=\"wp-image-34427\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0-1024x576.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0-300x169.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0-768x432.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0-1536x864.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/pe_gzj5uvz0.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">First FINSA est con\u00e7u pour am\u00e9liorer la confiance... Les clients peuvent \u00eatre assur\u00e9s que seuls les prestataires titulaires d'une autorisation sont autoris\u00e9s \u00e0 offrir des services financiers en Suisse. Tous les prestataires qui ont obtenu une autorisation de la FINMA sont soumis \u00e0 des contr\u00f4les r\u00e9guliers pour s'assurer qu'ils respectent les r\u00e8gles de la FINSA. Les clients peuvent \u00eatre s\u00fbrs qu'ils traitent avec un prestataire r\u00e9put\u00e9 lorsqu'ils font des affaires avec un prestataire titulaire d'une autorisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La loi sur les services financiers (LSFin) s'applique \u00e0 tous les prestataires de services financiers en Suisse. Cela comprend les banques, les compagnies d'assurance, les gestionnaires de patrimoine et toute autre entreprise qui fournit des services financiers aux consommateurs. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur son site FinSA, les banques fournissent des informations sur les derni\u00e8res exigences d\u00e9coulant de la loi f\u00e9d\u00e9rale suisse sur les services financiers (FinSA) et les mesures prises par les banques pour les mettre en pratique \u00e0 partir du 1er janvier 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cet article, nous pr\u00e9senterons les principaux aspects de FinSa et la mani\u00e8re dont InvestGlass CRM et PMS rel\u00e8vent ces d\u00e9fis. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-financial-sercices-act-finsa-definitions\"><span class=\"ez-toc-section\" id=\"Financial_sercices_act_FinSa_%E2%80%93_Definitions\"><\/span>Financial sercices act FinSa - D\u00e9finitions<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En vertu de la loi sur les services financiers, on entend par \"services financiers\" :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>l'acquisition ou la cession d'instruments financiers ;<\/li>\n\n\n\n<li>la r\u00e9ception et la transmission d'ordres portant sur des instruments financiers ;<\/li>\n\n\n\n<li>l'administration d'instruments financiers et d'instruments discr\u00e9tionnaires <a data-wpil-monitor-id=\"451\" href=\"https:\/\/www.investglass.com\/fr\/gerer-des-portefeuilles\/\" target=\"_blank\" rel=\"noopener\">gestion de portefeuille<\/a> \u00e9galement appel\u00e9e gestion centralis\u00e9e ;<\/li>\n\n\n\n<li>l'\u00e9mission de recommandations personnelles sur les transactions d'instruments financiers que nous appelons conseils en investissement ;<\/li>\n\n\n\n<li>l'octroi de pr\u00eats pour financer des op\u00e9rations sur instruments financiers ou des pr\u00eats lombards.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Un instrument financier est un titre ou un autre droit ou obligation contractuel qui conf\u00e8re \u00e0 son d\u00e9tenteur un int\u00e9r\u00eat financier dans un ou plusieurs actifs sous-jacents.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a transmission d'ordres de n\u00e9gociation lorsque vous achetez ou vendez une valeur mobili\u00e8re pour le compte d'une autre personne. Cela inclut le fait de passer un ordre aupr\u00e8s d'une institution financi\u00e8re pour acheter ou vendre un titre pour le compte d'une autre personne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une recommandation financi\u00e8re personnelle est un conseil en investissement donn\u00e9 \u00e0 un investisseur individuel. Il est important de rappeler que les recommandations financi\u00e8res personnelles ne doivent \u00eatre donn\u00e9es que par des conseillers en investissement qualifi\u00e9s et enregistr\u00e9s. Les fournisseurs non agr\u00e9\u00e9s ne sont pas autoris\u00e9s \u00e0 fournir des recommandations financi\u00e8res personnelles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les pr\u00eats lombards sont des pr\u00eats accord\u00e9s pour financer des transactions d'instruments financiers. Ces pr\u00eats sont g\u00e9n\u00e9ralement accord\u00e9s \u00e0 des particuliers ou \u00e0 des entreprises ayant de bons ant\u00e9c\u00e9dents en mati\u00e8re de cr\u00e9dit. Les cr\u00e9dits lombards sont des cr\u00e9dits \u00e0 court terme et le taux d'int\u00e9r\u00eat est g\u00e9n\u00e9ralement plus \u00e9lev\u00e9 que pour d'autres types de cr\u00e9dits.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm-1024x576.jpg\" alt=\"blocs de pr\u00eats au logement sur une surface en bois brun\" class=\"wp-image-34428\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm-1024x576.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm-300x169.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm-768x432.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm-1536x864.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/ohs6jmpuunm.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-and-financial-instruments-financial-services-are-regulated-with-finsa\"><span class=\"ez-toc-section\" id=\"And_financial_instruments_financial_services_are_regulated_with_FinSA\"><\/span>Les instruments financiers et les services financiers sont r\u00e9glement\u00e9s par la FinSA :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les titres de participation (actions, titres \u00e9quivalents \u00e0 des actions tels que les bons de participation donnant droit \u00e0 des dividendes et\/ou \u00e0 des droits de vote, ou titres convertibles en titres de participation) ;<\/li>\n\n\n\n<li>instruments de dette : titres non class\u00e9s comme titres de participation ;<\/li>\n\n\n\n<li>les parts d'organismes de placement collectif ;<\/li>\n\n\n\n<li>les produits structur\u00e9s ;<\/li>\n\n\n\n<li>d\u00e9riv\u00e9s ;<\/li>\n\n\n\n<li>les structures d'investissement priv\u00e9 ;<\/li>\n\n\n\n<li>les d\u00e9p\u00f4ts dont la valeur de remboursement ou le taux d'int\u00e9r\u00eat d\u00e9pend du risque ou du prix, \u00e0 l'exclusion de ceux dont le taux d'int\u00e9r\u00eat est li\u00e9 \u00e0 un indice de taux d'int\u00e9r\u00eat ;<\/li>\n\n\n\n<li>obligations : unit\u00e9s d'un emprunt global soumises \u00e0 des conditions uniformes.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-the-financial-service-provider-will-inform-their-customers\"><span class=\"ez-toc-section\" id=\"How_the_financial_service_provider_will_inform_their_customers\"><\/span>Comment le fournisseur de services financiers informera-t-il ses clients ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La plupart des obligations pr\u00e9vues par la loi f\u00e9d\u00e9rale sur les services financiers ne s'appliquent pas au segment des clients institutionnels. L'exp\u00e9rience professionnelle et l'activit\u00e9 r\u00e9glement\u00e9e par un organisme d'enregistrement prot\u00e8gent la banque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le client de d\u00e9tail, la protection du client est plus importante. La surveillance prudentielle est organis\u00e9e dans les documents publi\u00e9s par la banque et envoy\u00e9s aux clients de d\u00e9tail. Les conseillers, les banquiers et les responsables de la conformit\u00e9 b\u00e9n\u00e9ficieront \u00e9galement de tableaux de bord contenant toutes les informations pertinentes pour examiner les portefeuilles qui ne sont pas conformes au seuil de protection du client. InvestGlass produit ces documents et des avertissements automatis\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-riskindicator.jpeg\" alt=\"\" class=\"wp-image-32690\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-riskindicator.jpeg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-riskindicator-300x225.jpeg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-riskindicator-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">D\u00e9tection des risques InvestGlass<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-general-information-and-financial-institutions-acts-should-be-disclosed\"><span class=\"ez-toc-section\" id=\"General_information_and_financial_institutions_acts_should_be_disclosed\"><\/span>Informations g\u00e9n\u00e9rales et actes des institutions financi\u00e8res \u00e0 divulguer<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les banques et les courtiers doivent enregistrer et montrer quelle est leur supervision par la Suisse. <a href=\"https:\/\/www.investglass.com\/fr\/les-5-techniques-de-marketing-les-plus-efficaces-pour-les-services-financiers\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"452\">March\u00e9 financier<\/a> Autorit\u00e9 de surveillance \u201cFINMA\". De plus amples informations sont disponibles \u00e0 la Laupenstrasse 27, CH-3003 Berne, Suisse ou sur leur site web www.finma.ch.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-financial-services-under-the-swiss-financial-services-act-finsa\"><span class=\"ez-toc-section\" id=\"Financial_services_under_the_Swiss_Financial_Services_Act_FinSA\"><\/span>Services financiers au sens de la loi suisse sur les services financiers (LSFin)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les institutions financi\u00e8res doivent ensuite pr\u00e9senter les services offerts aux clients de d\u00e9tail, aux clients priv\u00e9s, aux clients institutionnels, aux clients professionnels et aux clients \u00e9trangers. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mandat de gestion discr\u00e9tionnaire - les actifs des clients seront g\u00e9r\u00e9s \u00e0 l'aide d'un outil de portefeuille mod\u00e8le. Le programme d'investissement et de r\u00e9\u00e9quilibrage est standardis\u00e9.<\/li>\n\n\n\n<li>On parle de mandat de conseil en investissement pour des portefeuilles entiers lorsqu'une institution financi\u00e8re accepte de prendre toutes les d\u00e9cisions d'investissement pour un client. Il s'agit notamment de d\u00e9cider quels titres acheter ou vendre, et \u00e0 quel moment prendre ces d\u00e9cisions. Les mandats de conseil en transactions sont ceux par lesquels une institution financi\u00e8re accepte de faire des recommandations sur des transactions d'instruments financiers sp\u00e9cifiques pour un client. Dans ce cas, le service de conseil peut collecter des informations provenant directement des champs du CRM avec une classification FINSA pour d\u00e9tecter l'ad\u00e9quation et les incompatibilit\u00e9s appropri\u00e9es. Si le client l'accepte, le conseiller peut appliquer une exception que nous appelons \"d\u00e9rogation\". Ces d\u00e9rogations sont collect\u00e9es et enregistr\u00e9es dans le rapport de contact.<\/li>\n\n\n\n<li>Les institutions financi\u00e8res qui fournissent des services autres que des recommandations financi\u00e8res personnelles, tels que la r\u00e9ception et la transmission d'ordres sur titres, sont tenues de divulguer ces informations \u00e0 leurs clients. Cette brochure donne un aper\u00e7u de la loi sur les services financiers (FinSA) et de la mani\u00e8re dont la banque se conformera \u00e0 la nouvelle r\u00e9glementation.<\/li>\n\n\n\n<li>Un pr\u00eat Lombard est un type de pr\u00eat \u00e0 court terme et le taux d'int\u00e9r\u00eat est g\u00e9n\u00e9ralement plus \u00e9lev\u00e9 que pour d'autres types de pr\u00eats.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"421\" height=\"207\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/appro_12ud7hs.png\" alt=\"\" class=\"wp-image-34431\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/appro_12ud7hs.png 421w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/appro_12ud7hs-300x148.png 300w\" sizes=\"(max-width: 421px) 100vw, 421px\" \/><figcaption class=\"wp-element-caption\">D\u00e9tection de l'ad\u00e9quation InvestGlass<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-who-is-the-mediation-body-of-the-financial-services-act\"><span class=\"ez-toc-section\" id=\"Who_is_the_Mediation_body_of_the_financial_services_act\"><\/span>Qui est l'organe de m\u00e9diation de la loi sur les services financiers ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les investisseurs peuvent s'adresser \u00e0 l'Ombudsman des banques suisses. L'organe de m\u00e9diation auquel les banques sont affili\u00e9es et situ\u00e9 Bahnhofplatz 9, case postale, CH-8021 Zurich, l'office de l'ombudsman. La proc\u00e9dure de m\u00e9diation, ainsi que toutes les informations utiles, sont disponibles sur le site Internet suivant : www.bankingombudsman.ch. Ils sont charg\u00e9s de la proc\u00e9dure de m\u00e9diation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-which-client-segmentation-is-defined\"><span class=\"ez-toc-section\" id=\"Which_Client_segmentation_is_defined\"><\/span>Quelle est la segmentation de la client\u00e8le d\u00e9finie ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En vertu de la loi f\u00e9d\u00e9rale suisse sur les services financiers, les banques et les courtiers, en tant que prestataires de services financiers, sont tenus d'affecter chacun de leurs clients \u00e0 l'un des trois segments suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>priv\u00e9s, commun\u00e9ment appel\u00e9s clients de d\u00e9tail,<\/li>\n\n\n\n<li>les clients professionnels ou les investisseurs institutionnels<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette classification se fait sur la base des principes suivants :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les clients priv\u00e9s sont des clients qui ne sont ni des investisseurs professionnels ni des investisseurs institutionnels ;<\/li>\n\n\n\n<li>Les clients professionnels sont des clients tels que les entreprises ayant des op\u00e9rations de tr\u00e9sorerie professionnelles, les institutions de retraite professionnelle et les organismes de droit public, qui poss\u00e8dent un niveau \u00e9lev\u00e9 de connaissances et d'exp\u00e9rience dans les domaines financiers ;<\/li>\n\n\n\n<li>Les clients institutionnels sont des clients tels que les banques, les organismes de placement collectif, les compagnies d'assurance et d'autres interm\u00e9diaires financiers soumis \u00e0 une surveillance prudentielle en Suisse ou \u00e0 l'\u00e9tranger, qui, en raison de leur statut, de leur structure et de leurs ressources financi\u00e8res, sont consid\u00e9r\u00e9s comme ayant un niveau \u00e9lev\u00e9 de sophistication dans les domaines financiers.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette d\u00e9finition peut varier l\u00e9g\u00e8rement d'une banque \u00e0 l'autre. Les clients professionnels sont consid\u00e9r\u00e9s comme des investisseurs avertis dont le niveau de protection est moins \u00e9lev\u00e9 que celui des clients de d\u00e9tail, en raison de leur niveau de connaissance et d'exp\u00e9rience et de leur capacit\u00e9 \u00e0 supporter des pertes financi\u00e8res.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les clients priv\u00e9s b\u00e9n\u00e9ficient du niveau de protection le plus \u00e9lev\u00e9 en vertu de la loi sur les services financiers (FinSA). Ils sont d\u00e9finis comme des clients qui ne sont ni des investisseurs professionnels ni des investisseurs institutionnels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9duction du niveau de protection et le changement de classification en faveur du client professionnel ou du client institutionnel modifient la protection du client.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si les clients class\u00e9s comme particuliers ou professionnels souhaitent \u00eatre class\u00e9s dans un segment offrant un niveau de protection inf\u00e9rieur et qu'ils remplissent les conditions pr\u00e9vues \u00e0 cet effet, ils doivent en informer leur banquier ou leur vendeur. Celui-ci leur remettra un formulaire de renonciation \u00e0 la classification. Cela aura une incidence sur l'ad\u00e9quation et la pertinence de la classification. <a href=\"https:\/\/www.investglass.com\/fr\/tests-de-resistance-des-portefeuilles\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"453\">test de la gestion de portefeuille<\/a> l'outil et l'interaction avec le CRM seront \u00e9galement diff\u00e9rents.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-crm.jpeg\" alt=\"\" class=\"wp-image-32677\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-crm.jpeg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-crm-300x225.jpeg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-crm-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass CRM<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-verification-of-suitability-and-appropriateness-is-the-core-added-value-of-the-investglass-swiss-cloud-solution\"><span class=\"ez-toc-section\" id=\"Verification_of_suitability_and_appropriateness_is_the_core_added_value_of_the_InvestGlass_Swiss_Cloud_Solution\"><\/span>La v\u00e9rification de l'ad\u00e9quation et de la pertinence est la principale valeur ajout\u00e9e de la solution InvestGlass Swiss Cloud.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-discretionary-asset-management-mandates\"><span class=\"ez-toc-section\" id=\"Discretionary_asset_management_mandates\"><\/span>Mandats de gestion d'actifs discr\u00e9tionnaires<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu'un client confie \u00e0 une banque un mandat de gestion discr\u00e9tionnaire, la banque s'assure que le mandat de gestion discr\u00e9tionnaire est bien ex\u00e9cut\u00e9. <em>strat\u00e9gie d'investissement<\/em> que le client a choisi est appropri\u00e9, compte tenu de son profil de risque. Le profil de risque est un \u00e9l\u00e9ment cl\u00e9 de la relation et se fonde sur les informations communiqu\u00e9es par le client sur sa situation personnelle, ses objectifs d'investissement et son app\u00e9tit pour le risque. Il permet \u00e0 la Banque de comprendre les besoins du client et de recommander une strat\u00e9gie d'investissement qui r\u00e9ponde au mieux \u00e0 ces besoins. Il est donc essentiel que les clients communiquent des informations compl\u00e8tes et exactes. Le profil de risque est r\u00e9guli\u00e8rement revu par la Banque en collaboration avec le client. Ces \u00e9l\u00e9ments d'ad\u00e9quation sont d'abord enregistr\u00e9s \u00e0 partir des formulaires d'enregistrement InvetGlass Digital qui enregistrent tous les r\u00e9sultats dans le CRM.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"799\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/edit-custom_ztqvqh-1-1024x799.png\" alt=\"\" class=\"wp-image-34432\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/edit-custom_ztqvqh-1-1024x799.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/edit-custom_ztqvqh-1-300x234.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/edit-custom_ztqvqh-1-768x599.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/edit-custom_ztqvqh-1.png 1118w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass CRM est con\u00e7u pour l'automatisation de FINSA<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-advisory-mandates-for-an-entire-portfolio\"><span class=\"ez-toc-section\" id=\"Advisory_mandates_for_an_entire_portfolio\"><\/span>Mandats de conseil pour l'ensemble d'un portefeuille<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les mandats de conseil portant sur des portefeuilles entiers, la banque s'assure de l'ad\u00e9quation de la strat\u00e9gie d'investissement de la m\u00eame mani\u00e8re que pour les mandats de gestion discr\u00e9tionnaire.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour tout conseil en investissement relatif \u00e0 un instrument financier offert par la Banque, celle-ci v\u00e9rifie d'une part que l'instrument financier est adapt\u00e9 \u00e0 la strat\u00e9gie d'investissement convenue et, d'autre part, que le client dispose des connaissances suffisantes pour comprendre les risques li\u00e9s \u00e0 l'instrument concern\u00e9 (v\u00e9rification de l'ad\u00e9quation). Le cas \u00e9ch\u00e9ant, la Banque avertit son client si l'instrument financier n'est pas adapt\u00e9 ou appropri\u00e9 \u00e0 son cas particulier. Ces \u00e9l\u00e9ments sont document\u00e9s par le <a href=\"https:\/\/www.investglass.com\/fr\/comment-creer-sa-propre-banque-privee\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"454\">Banque pour ses activit\u00e9s priv\u00e9es<\/a> clients.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-healthcheck-portfolio.jpeg\" alt=\"\" class=\"wp-image-32682\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-healthcheck-portfolio.jpeg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-healthcheck-portfolio-300x225.jpeg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-healthcheck-portfolio-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Bilan de sant\u00e9 d'InvestGlass<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-advisory-transaction-mandates\"><span class=\"ez-toc-section\" id=\"Advisory_transaction_mandates\"><\/span>Mandats de conseil en transactions<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui concerne les conseils demand\u00e9s par un client sur une transaction dans un instrument financier offert par la Banque, la Banque v\u00e9rifie si le client est en mesure de comprendre les risques li\u00e9s \u00e0 cet instrument financier. Le cas \u00e9ch\u00e9ant, la Banque avertit son client si l'instrument financier n'est pas appropri\u00e9 dans son cas particulier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, dans le cas d'un mandat de conseil, la Banque ne v\u00e9rifie pas l'ad\u00e9quation de la transaction, puisqu'elle ne conna\u00eet pas le profil de risque du client ni son portefeuille.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-transaction-execution-without-advice\"><span class=\"ez-toc-section\" id=\"Transaction_execution_without_advice\"><\/span>Ex\u00e9cution de la transaction (sans conseil)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En l'absence de mandat de gestion de fortune discr\u00e9tionnaire ou de mandat de conseil, la Banque ne proc\u00e8de \u00e0 aucun contr\u00f4le d'ad\u00e9quation ou de pertinence lorsqu'elle ex\u00e9cute un ordre portant sur des instruments financiers communiqu\u00e9 par un client, quelle que soit sa classification de client priv\u00e9 ou professionnel). Dans le cas d'une ex\u00e9cution de transaction sans conseil, la banque attire express\u00e9ment l'attention de son client sur le fait qu'elle n'effectue aucun contr\u00f4le d'ad\u00e9quation ou de pertinence, que le client soit priv\u00e9, professionnel ou institutionnel. La Banque ne r\u00e9it\u00e8re pas cet avertissement \u00e0 un stade ult\u00e9rieur de la relation contractuelle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-clients-acting-through-an-external-asset-manager-gerant-independant-ifa\"><span class=\"ez-toc-section\" id=\"Clients_acting_through_an_external_asset_manager_Gerant_independant_IFA\"><\/span>Clients agissant par l'interm\u00e9diaire d'un gestionnaire de fortune externe (G\u00e9rant ind\u00e9pendant, IFA)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si un client d\u00e9signe un gestionnaire de fortune externe pour g\u00e9rer les avoirs confi\u00e9s \u00e0 la banque, la Banque agit en tant que banque d\u00e9positaire et ex\u00e9cute les ordres d'investissement communiqu\u00e9s par le client ou son gestionnaire externe, le cas \u00e9ch\u00e9ant, sur la base de la procuration accord\u00e9e par le client au gestionnaire externe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0-1024x683.jpg\" alt=\"femme en chemise noire utilisant un macbook\" class=\"wp-image-34429\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0-1024x683.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0-300x200.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0-768x512.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0-1536x1024.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/dowrnum2di0.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass rend l'interaction avec les clients facile et sans friction<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-appropriateness-in-the-event-of-a-lombard-loan-application\"><span class=\"ez-toc-section\" id=\"Appropriateness_in_the_event_of_a_Lombard_loan_application\"><\/span>Ad\u00e9quation en cas de demande de cr\u00e9dit lombard<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La banque fournira des informations sur les risques sp\u00e9cifiques li\u00e9s \u00e0 l'utilisation des cr\u00e9dits lombards. Si les clients professionnels ou priv\u00e9s disposent d'un mandat de gestion de fortune discr\u00e9tionnaire ou d'un mandat de conseil, la Banque les conseillera \u00e9galement sur l'ad\u00e9quation du montant du cr\u00e9dit qu'ils sollicitent. Si, en raison du montant du cr\u00e9dit, le profil de risque ne correspond plus \u00e0 celui initialement convenu, la Banque en informera le client et examinera la situation avec son client, afin d'\u00e9tudier des solutions alternatives.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-financial-relationships-with-third-parties-and-management-companies\"><span class=\"ez-toc-section\" id=\"Financial_relationships_with_third_parties_and_management_companies\"><\/span>Relations financi\u00e8res avec des tiers et des soci\u00e9t\u00e9s de gestion<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cas de mandats de conseil en transactions ou de services d'ex\u00e9cution de transactions sans conseil, la banque recevra des paiements de soci\u00e9t\u00e9s tierces li\u00e9s \u00e0 l'acquisition de placements collectifs de capitaux. La banque conserve ces montants et informe le client du type et du montant de la r\u00e9mun\u00e9ration qu'elle a re\u00e7ue. Un portail client est donc n\u00e9cessaire pour faciliter le transfert d'une grande quantit\u00e9 d'informations. InvestGlass peut \u00eatre utilis\u00e9 pour l'enregistrement des informations relatives aux produits structur\u00e9s, par exemple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si le client a accord\u00e9 une autorisation discr\u00e9tionnaire <a href=\"https:\/\/www.investglass.com\/fr\/gestion-de-portefeuille-pour-les-esg\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"455\">mandat de gestion d'actifs ou mandat de conseil pour l'ensemble d'un portefeuille<\/a>, La banque ne re\u00e7oit pas ces paiements ou les recr\u00e9dite int\u00e9gralement au client. Les montants recr\u00e9dit\u00e9s sont indiqu\u00e9s sur le relev\u00e9 de compte annuel dans la vue de gestion du portefeuille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vue du portefeuille peut \u00eatre personnalis\u00e9e pour r\u00e9pondre aux besoins des clients professionnels ou particuliers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-best-execution-of-client-orders\"><span class=\"ez-toc-section\" id=\"Best_execution_of_client_orders\"><\/span>Meilleure ex\u00e9cution des ordres des clients<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La banque a mis en place toutes les mesures n\u00e9cessaires pour obtenir le meilleur r\u00e9sultat possible dans l'ex\u00e9cution des ordres des clients, que ce soit en termes de prix, de co\u00fbt, de rapidit\u00e9, de probabilit\u00e9 d'ex\u00e9cution et de r\u00e8glement, de taille, de nature de l'ordre, ou de toute autre consid\u00e9ration impliqu\u00e9e dans l'ex\u00e9cution de l'ordre, ce que nous appelons les facteurs d'ex\u00e9cution. InvestGlass est connect\u00e9 \u00e0 un outil de gestion des ordres d'une tierce partie. Ces mesures s'appliquent ind\u00e9pendamment du fait qu'un ordre soit ex\u00e9cut\u00e9 par la Banque ou communiqu\u00e9 \u00e0 un tiers pour ex\u00e9cution.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e8gle g\u00e9n\u00e9rale, une attention particuli\u00e8re est accord\u00e9e au prix et aux co\u00fbts afin de garantir le meilleur r\u00e9sultat possible. Toutefois, pour certains ordres, instruments financiers, march\u00e9s ou conditions de march\u00e9, d'autres facteurs d'ex\u00e9cution peuvent \u00eatre tout aussi importants ou primer le prix pour garantir la meilleure ex\u00e9cution possible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-basic-factsheet-and-collective-investment-schemes-act-nbsp-cisa\"><span class=\"ez-toc-section\" id=\"Basic_factsheet_and_Collective_Investment_Schemes_Act_CISA\"><\/span>Fiche d'information et loi sur les placements collectifs de capitaux LPCC<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La fiche de base, le document d'informations cl\u00e9s (ou son \u00e9quivalent, publi\u00e9 conform\u00e9ment \u00e0 la l\u00e9gislation et \u00e0 la r\u00e9glementation europ\u00e9ennes) contient des informations sur les \u00e9l\u00e9ments cl\u00e9s de certains instruments financiers, notamment :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- le nom de l'instrument ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- le type d'investissement ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- les risques li\u00e9s \u00e0 l'investissement ;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- comment contacter l'autorit\u00e9 comp\u00e9tente en cas de probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le fonds europ\u00e9en KIID contient toutes les informations dont vous avez besoin. <a href=\"https:\/\/www.investglass.com\/fr\/esg-et-finance-durable-ce-quil-faut-savoir\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"456\">besoin de savoir<\/a> sur un produit financier, y compris le nom du produit, le type d'investissement, les risques associ\u00e9s \u00e0 l'investissement et la mani\u00e8re de contacter l'autorit\u00e9 comp\u00e9tente en cas de probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La loi sur les organismes de placement collectif (Collective Investment Schemes Act CISA) est un produit d'investissement qui permet aux investisseurs de mettre leur argent en commun avec d'autres investisseurs afin d'investir dans un large \u00e9ventail d'actifs. Ces organismes peuvent \u00eatre ouverts ou ferm\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sachez \u00e9galement que <a href=\"https:\/\/www.investglass.com\/fr\/comment-les-banquiers-peuvent-gerer-lallocation-a-vie-des-pensions-au-royaume-uni\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"457\">gestionnaires des actifs des r\u00e9gimes de retraite professionnelle<\/a> qui \u00e9taient auparavant surveill\u00e9s par la Commission de surveillance de la pr\u00e9voyance professionnelle (CSFP), seront d\u00e9sormais soumis \u00e0 la surveillance de la FINMA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les rapports de contact d'InvestGlass sont construits pour stocker ces KIID et ces fiches d'information de base. InvestGlass CRM - L'outil de campagne enverra \u00e0 votre client un e-mail avec le PDF du KIID et de la fiche d'information de base \u00e0 stocker dans le dossier du client.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-email-marketing.jpeg\" alt=\"\" class=\"wp-image-32681\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-email-marketing.jpeg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-email-marketing-300x225.jpeg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-email-marketing-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass Email &amp; Campagne<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-risks-associated-with-financial-instruments-and-finsa\"><span class=\"ez-toc-section\" id=\"Risks_associated_with_financial_instruments_and_FINSA\"><\/span>Risques li\u00e9s aux instruments financiers et \u00e0 FINSA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La banque doit informer tous ses clients des risques li\u00e9s aux instruments financiers. Une brochure intitul\u00e9e \u201cRisques li\u00e9s au n\u00e9goce d'instruments financiers\u201d et \u00e9dit\u00e9e par l'Association Bancaire Suisse est remise au client particulier et au client professionnel lors de l'ouverture de leur compte et en tout temps sur demande. Ces informations sont \u00e9galement disponibles sur le site Internet de l'Association suisse des banques \u00e0 l'adresse suivante : www.swissbanking.ch\/en\/downloads<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, la Banque met \u00e9galement \u00e0 la disposition de tous ses clients sa brochure intitul\u00e9e \u201c Information sur les risques li\u00e9s aux op\u00e9rations sur produits d\u00e9riv\u00e9s standardis\u00e9s et non standardis\u00e9s\/produits structur\u00e9s et fonds d'investissement \u00e0 risques particuliers \u201d, qui d\u00e9crit les risques applicables \u00e0 certains instruments financiers sp\u00e9cifiques. La Banque <a href=\"https:\/\/www.investglass.com\/fr\/crm-pour-banque-privee\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1291\">la banque devrait \u00e9galement stocker dans le CRM<\/a> la formation personnelle du client, son exp\u00e9rience professionnelle ou une exp\u00e9rience comparable dans le secteur financier, m\u00eame si la plupart des obligations pr\u00e9vues par la loi f\u00e9d\u00e9rale suisse sur les services financiers ne s'appliquent pas \u00e0 ce segment de client\u00e8le professionnelle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-information-on-costs-and-charges\"><span class=\"ez-toc-section\" id=\"Information_on_costs_and_charges\"><\/span><strong>Informations sur les co\u00fbts et les frais<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avec les outils de gestion de portefeuille InvestGlass, les banques et les courtiers peuvent communiquer tous les co\u00fbts et frais li\u00e9s aux services financiers qu'ils fournissent. Le bar\u00e8me des frais est contenu dans un document remis \u00e0 tous les nouveaux clients avant la prestation du service concern\u00e9. Ce document est disponible sur demande \u00e0 tout moment. La communication peut \u00eatre partag\u00e9e avec le client priv\u00e9 par SMS, Email ou via le portail client InvestGlass.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">InvestGlass peut aider \u00e0 automatiser le processus FINSA en fournissant un CRM qui inclut toutes les informations et la documentation n\u00e9cessaires. <a href=\"https:\/\/www.investglass.com\/fr\/crm-pour-fina\/\">CRM d'InvestGlass <\/a>est con\u00e7u pour rationaliser le processus de collecte et d'organisation des informations, et il comprend une multitude de fonctionnalit\u00e9s qui facilitent la gestion de la conformit\u00e9 FINSA. Par exemple, InvestGlass permet aux utilisateurs de suivre les interactions avec les clients, de g\u00e9rer les documents des clients et de g\u00e9n\u00e9rer des rapports. En outre, le CRM d'InvestGlass est int\u00e9gr\u00e9 au syst\u00e8me de d\u00e9p\u00f4t en ligne de la FINSA, ce qui facilite le d\u00e9p\u00f4t de rapports conformes. InvestGlass peut donc simplifier consid\u00e9rablement le processus de conformit\u00e9 aux exigences de la FINSA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><span style=\"text-decoration: underline;\">IL NE S'AGIT PAS D'UN AVIS JURIDIQUE - VEUILLEZ CONSULTER VOTRE PROPRE CONSEILLER JURIDIQUE.<\/span><\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>THIS IS NOT A LEGAL ADVICE &#8211; PLEASE CONSULT YOUR OWN LEGAL ADVISOR. As of January 1, 2018, the Financial Services Act (FinSA) came into effect in Switzerland (Federal Council shall regulate new details). The new act replaces the old Banking Act and regulates all financial services providers in Switzerland. The main purpose of the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34424,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[288,295,296,72],"class_list":["post-34423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-client-life-cycle","tag-fidleg","tag-financial-services-act","tag-finsa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How to implement FINSA? | InvestGlass<\/title>\n<meta name=\"description\" content=\"Only FINMA-approved providers get licensed. See how InvestGlass automates compliance for banks.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/fr\/comment-mettre-en-oeuvre-le-fina\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to implement FINSA?\" \/>\n<meta property=\"og:description\" content=\"THIS IS NOT A LEGAL ADVICE - PLEASE CONSULT YOUR OWN LEGAL ADVISOR. As of January 1, 2018, the Financial Services Act (FinSA) came into effect in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/fr\/comment-mettre-en-oeuvre-le-fina\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-27T06:23:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T08:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment mettre en \u0153uvre FINSA ? | InvestGlass","description":"Seuls les fournisseurs approuv\u00e9s par la FINMA obtiennent une licence. D\u00e9couvrez comment InvestGlass automatise la conformit\u00e9 pour les banques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/fr\/comment-mettre-en-oeuvre-le-fina\/","og_locale":"fr_FR","og_type":"article","og_title":"How to implement FINSA?","og_description":"THIS IS NOT A LEGAL ADVICE - PLEASE CONSULT YOUR OWN LEGAL ADVISOR. As of January 1, 2018, the Financial Services Act (FinSA) came into effect in","og_url":"https:\/\/www.investglass.com\/fr\/comment-mettre-en-oeuvre-le-fina\/","og_site_name":"InvestGlass","article_published_time":"2022-08-27T06:23:10+00:00","article_modified_time":"2025-02-24T08:42:44+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"\u00c9crit par":"InvestGlass","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"How to implement FINSA?","datePublished":"2022-08-27T06:23:10+00:00","dateModified":"2025-02-24T08:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/"},"wordCount":2935,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg","keywords":["client life cycle","FIDLEG","Financial Services Act","FINSA"],"articleSection":["Article"],"inLanguage":"fr-FR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/fr\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/","url":"https:\/\/www.investglass.com\/how-to-implement-finsa\/","name":"Comment mettre en \u0153uvre FINSA ? | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg","datePublished":"2022-08-27T06:23:10+00:00","dateModified":"2025-02-24T08:42:44+00:00","description":"Seuls les fournisseurs approuv\u00e9s par la FINMA obtiennent une licence. D\u00e9couvrez comment InvestGlass automatise la conformit\u00e9 pour les banques.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/how-to-implement-finsa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/cpg4m2ab0e.jpg","width":1600,"height":1067,"caption":"train at middle of street surrounded by buildings"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"How to implement FINSA?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"Le CRM souverain suisse","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/fr\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investglass.com\/how-to-implement-finsa\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts\/34423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/comments?post=34423"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts\/34423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/media\/34424"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/media?parent=34423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/categories?post=34423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/tags?post=34423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}