{"id":30443,"date":"2021-07-08T13:16:56","date_gmt":"2021-07-08T11:16:56","guid":{"rendered":"https:\/\/www.investglass.com\/?p=30443"},"modified":"2025-03-19T06:19:12","modified_gmt":"2025-03-19T05:19:12","slug":"generation-z-les-differences-entre-les-milleniaux-et-ce-quil-faut-savoir","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/fr\/generation-z-how-millenials-are-different-and-what-we-should-know\/","title":{"rendered":"G\u00e9n\u00e9ration Z : En quoi les Millennials sont diff\u00e9rents et ce qu'il faut savoir ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les mill\u00e9niaux ont longtemps \u00e9t\u00e9 au centre des strat\u00e9gies marketing en raison de leur pouvoir d'achat substantiel et de leur ma\u00eetrise technologique. Cependant, une nouvelle cohorte, la g\u00e9n\u00e9ration Z, n\u00e9e entre 1997 et 2012, \u00e9merge comme une base de consommateurs importante. En 2024, la g\u00e9n\u00e9ration Z repr\u00e9sente environ\u00a0<strong>28% de la population mondiale<\/strong>, ce qui se traduit par plus de\u00a0<strong>2,2 milliards d'individus dans le monde<\/strong>\u00a0(<a href=\"https:\/\/www.maverish.com\/statistics\/gen-z-statistics\/\">Maverish<\/a>). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette g\u00e9n\u00e9ration se caract\u00e9rise par sa diversit\u00e9 raciale et ethnique.\u00a0<strong>50% des membres de la g\u00e9n\u00e9ration Z appartiennent \u00e0 des minorit\u00e9s raciales et ethniques<\/strong>, avec\u00a0<strong>1 personne sur 4 s'identifie comme hispanique<\/strong>\u00a0(<a href=\"https:\/\/www.britannica.com\/topic\/Generation-Z\">Britannica<\/a>). Sur le plan financier, la g\u00e9n\u00e9ration Z exerce une influence consid\u00e9rable.\u00a0<strong>$360 milliards<\/strong>, Selon les projections, elle devrait repr\u00e9senter jusqu'\u00e0\u00a0<strong>30% d'achats de luxe d'ici 2030<\/strong>\u00a0(<a>Vogue Business<\/a>). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les mill\u00e9niaux sont \u00e0 l'avant-garde de la <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/fr\/outils-de-marketing\/\" target=\"_blank\"  rel=\"noopener\" title=\"marketing\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"4990\">marketing<\/a> et de la publicit\u00e9. Ils sont faciles \u00e0 comprendre, ont un pouvoir d'achat \u00e9lev\u00e9 et sont \u00e0 l'aise avec la technologie. Mais une nouvelle g\u00e9n\u00e9ration se profile \u00e0 l'horizon : La g\u00e9n\u00e9ration Z, celle qui est n\u00e9e apr\u00e8s 1995. Ce nouveau groupe est sur le point d'entrer dans l'\u00e2ge adulte d'ici une dizaine d'ann\u00e9es - et il est temps que les sp\u00e9cialistes du marketing commencent \u00e0 se pr\u00e9parer pour lui. Cherchez-vous \u00e0 cr\u00e9er une n\u00e9o-banque pour la g\u00e9n\u00e9ration Z ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que savons-nous de cette nouvelle g\u00e9n\u00e9ration ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous pr\u00e9sentons dans cet article huit diff\u00e9rences essentielles. Ils sont \u00e9galement connus sous le nom de post-millennials et sont un peu diff\u00e9rents des millennials. Il y a beaucoup \u00e0 apprendre sur ce groupe de consommateurs. <a href=\"https:\/\/www.investglass.com\/fr\/ce-quil-faut-savoir-avant-de-creer-sa-banque-numerique\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"445\">ce qu'il faut savoir<\/a> si vous vous adressez \u00e0 eux :<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-generation-z-is-much-more-entrepreneurial-than-previous-generations-43-want-to-start-their-own-business\"><span class=\"ez-toc-section\" id=\"1_Generation_Z_is_much_more_entrepreneurial_than_previous_generations_%E2%80%93_43_want_to_start_their_own_business\"><\/span><strong>1) La g\u00e9n\u00e9ration Z est beaucoup plus entreprenante que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes - 43% veulent cr\u00e9er leur propre entreprise.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La g\u00e9n\u00e9ration Z est une g\u00e9n\u00e9ration avide d'entrepreneuriat qui cherche \u00e0 cr\u00e9er son propre impact sur la soci\u00e9t\u00e9 et le monde des affaires. Ils pr\u00e9f\u00e8rent avoir leur propre espace de travail, ils sont natifs du num\u00e9rique, ils pr\u00e9f\u00e8rent les communications hors ligne sur le lieu de travail et une structure organisationnelle plate. Ils ont \u00e9galement tendance \u00e0 rechercher des employeurs ayant la m\u00eame culture de la demande et la m\u00eame mentalit\u00e9 de bricolage. C'est la seule g\u00e9n\u00e9ration qui souhaite profond\u00e9ment influer sur la structure organisationnelle, qui explore les alternatives en mati\u00e8re d'\u00e9ducation et qui fait preuve d'une grande compr\u00e9hension, tout en pr\u00e9f\u00e9rant toujours communiquer en face \u00e0 face. La g\u00e9n\u00e9ration Z comprend que l'entreprise 0 papier est essentielle.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-1024x683.jpg\" alt=\"personne tenant la main d&#039;un b\u00e9b\u00e9\" class=\"wp-image-31823\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-1024x683.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-300x200.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-768x512.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-1536x1024.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-1080x720.jpg 1080w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-1280x854.jpg 1280w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-980x654.jpg 980w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork-480x320.jpg 480w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/teamwork.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-generation-z-gen-z-has-been-described-as-civic-or-global-citizens-because-they-care-about-social-issues-and-problems-in-the-world\"><span class=\"ez-toc-section\" id=\"2_Generation_Z_Gen_Z_has_been_described_as_%E2%80%9Ccivic%E2%80%9D_or_%E2%80%9Cglobal_citizens%E2%80%9D_because_they_care_about_social_issues_and_problems_in_the_world\"><\/span>2) La g\u00e9n\u00e9ration Z a \u00e9t\u00e9 d\u00e9crite comme \u201ccivique\u201d ou \u201ccitoyenne du monde\u201d parce qu'elle se pr\u00e9occupe des questions sociales et des probl\u00e8mes dans le monde.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La g\u00e9n\u00e9ration Z est diff\u00e9rente de la g\u00e9n\u00e9ration du mill\u00e9naire lorsqu'il s'agit d'\u00e9v\u00e9nements mondiaux importants li\u00e9s \u00e0 des questions environnementales et sociales. Elle se pr\u00e9occupe non seulement de son propre peuple et de son propre pays, mais aussi des jeunes adultes et des jeunes du monde entier. Elle est la g\u00e9n\u00e9ration la plus sensible en ce qui concerne <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/fr\/gerer-des-portefeuilles\/\" target=\"_blank\" rel=\"noopener\" title=\"GSE\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"709\">GSE<\/a> de toute autre g\u00e9n\u00e9ration qui pr\u00e9c\u00e8de. InvestGlass <a href=\"https:\/\/www.investglass.com\/fr\/gestion-de-portefeuille-pour-les-esg\/\">outil de gestion de portefeuille<\/a> a \u00e9t\u00e9 con\u00e7u pour offrir des \u201cmod\u00e8les\u201d pour chaque segment de client\u00e8le. Ainsi, vous pouvez offrir une vue diff\u00e9rente aux clients qui recherchent des investisseurs ESG ou obligataires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-the-majority-of-generation-z-prefer-face-to-face-communication-over-digital-platforms\"><span class=\"ez-toc-section\" id=\"3_The_majority_of_generation_z_prefer_face-to-face_communication_over_digital_platforms\"><\/span>3) La majorit\u00e9 des membres de la g\u00e9n\u00e9ration z pr\u00e9f\u00e8rent la communication en face \u00e0 face aux plateformes num\u00e9riques<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La g\u00e9n\u00e9ration z est la g\u00e9n\u00e9ration post-mill\u00e9naire, et le seul groupe de la jeune g\u00e9n\u00e9ration, qui sont les natifs num\u00e9riques de l'\u00e8re num\u00e9rique. Elle est la premi\u00e8re g\u00e9n\u00e9ration mondiale \u00e0 \u00eatre n\u00e9e \u00e0 l'\u00e8re des multiples outils de communication num\u00e9rique, des moteurs de recherche, des tutoriels sur YouTube, de la vid\u00e9o \u00e0 la demande et de la messagerie instantan\u00e9e. Mais contrairement aux jeunes g\u00e9n\u00e9rations d'aujourd'hui qui vivent \u00e9ternellement en ligne, ils pr\u00e9f\u00e8rent \u00e9galement vivre dans le monde physique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-1024x768.jpg\" alt=\"pi\u00e8ce de monnaie tezos\" class=\"wp-image-31824\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-1024x768.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-300x225.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-768x576.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-1536x1152.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-510x382.jpg 510w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-1080x810.jpg 1080w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-1280x960.jpg 1280w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-980x735.jpg 980w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3-480x360.jpg 480w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/tezos3.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-realistic-gen-z-vs-optimistic-baby-boomers\"><span class=\"ez-toc-section\" id=\"4_Realistic_Gen_z_vs_Optimistic_Baby_Boomers\"><\/span>4) R\u00e9aliste (G\u00e9n\u00e9ration Z) vs Optimiste (Baby Boomers)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Soixante-dix-sept pour cent des membres de la g\u00e9n\u00e9ration Z s'attendent \u00e0 travailler plus dur que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes. Les mill\u00e9niaux sont devenus optimistes gr\u00e2ce aux encouragements de leurs parents baby-boomers et au fait qu'ils ont grandi dans une p\u00e9riode de prosp\u00e9rit\u00e9 et d'opportunit\u00e9s. La g\u00e9n\u00e9ration Z sera r\u00e9aliste gr\u00e2ce \u00e0 ses parents de la g\u00e9n\u00e9ration X, sceptiques et directs, qui ont grandi dans une p\u00e9riode de r\u00e9cession. Votre approche commerciale et <a href=\"https:\/\/www.investglass.com\/fr\/july-is-a-slow-month-its-time-to-re-think-the-stages-of-the-customer-life-cycle\/\">le cycle de vente sera diff\u00e9rent<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-more-trust-to-government-than-in-businesses\"><span class=\"ez-toc-section\" id=\"5_More_trust_to_government_than_in_businesses\"><\/span>5) Plus de confiance envers le gouvernement qu'envers les entreprises.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La g\u00e9n\u00e9ration Z est plus encline que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes \u00e0 se tourner vers le gouvernement pour r\u00e9soudre les probl\u00e8mes, plut\u00f4t que vers les entreprises et les particuliers. Sept membres de la g\u00e9n\u00e9ration Z sur dix estiment que le gouvernement devrait faire davantage pour r\u00e9soudre les probl\u00e8mes, tandis que 29% estiment que le gouvernement fait trop de choses qu'il vaudrait mieux laisser aux entreprises et aux particuliers. Par ailleurs, les g\u00e9n\u00e9rations plus \u00e2g\u00e9es font davantage confiance aux individus et \u00e0 leurs pairs du monde entier que la g\u00e9n\u00e9ration Z.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-private-life-vs-public-nbsp-life\"><span class=\"ez-toc-section\" id=\"6_Private_life_vs_Public_life\"><\/span>6) Vie priv\u00e9e et vie publique<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La g\u00e9n\u00e9ration z se distingue de la g\u00e9n\u00e9ration des mill\u00e9niaux et des baby-boomers \u00e0 bien des \u00e9gards. L'une d'entre elles est leur attitude \u00e0 l'\u00e9gard de la vie priv\u00e9e et des informations personnelles sur les r\u00e9seaux sociaux. Les membres de la g\u00e9n\u00e9ration du mill\u00e9naire ont \u00e9t\u00e9 les pionniers du num\u00e9rique \u00e0 l'\u00e8re moderne. Ils ont assist\u00e9 \u00e0 l'introduction et \u00e0 l'essor des m\u00e9dias sociaux, de la messagerie instantan\u00e9e, des smartphones, des moteurs de recherche et de la r\u00e9volution mobile. La g\u00e9n\u00e9ration Z n'a pas \u00e9t\u00e9 t\u00e9moin de ces innovations, elle y est n\u00e9e. La connectivit\u00e9 omnipr\u00e9sente, les appareils mobiles puissants, l'information mondiale hautement conserv\u00e9e et les cycles d'information 24 heures sur 24 et 7 jours sur 7 sont le propre de la g\u00e9n\u00e9ration Z. Soixante-dix pour cent des membres de la g\u00e9n\u00e9ration Z pr\u00e9f\u00e9reraient partager des informations personnelles avec leur animal de compagnie plut\u00f4t qu'avec leur patron.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-1024x683.jpg\" alt=\"trois femmes marchant sur un quai en bois brun pr\u00e8s d&#039;un immeuble de grande hauteur pendant la journ\u00e9e\" class=\"wp-image-31826\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-1024x683.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-300x200.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-768x512.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-1536x1024.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-1080x720.jpg 1080w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-1280x854.jpg 1280w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-980x654.jpg 980w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1-480x320.jpg 480w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/mkjuozpy70i-1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-lower-birthrate-with-regards-to-generation-z-s-parents\"><span class=\"ez-toc-section\" id=\"7_Lower_birthrate_with_regards_to_generation_Zs_parents\"><\/span>7) Un taux de natalit\u00e9 plus faible que celui des parents de la g\u00e9n\u00e9ration Z<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cette g\u00e9n\u00e9ration \u00e9mergente sera moins nombreuse que ses a\u00een\u00e9s en raison d'un taux de natalit\u00e9 qui n'a jamais \u00e9t\u00e9 aussi bas. Le groupe cible sera donc plus restreint, puisqu'il ne repr\u00e9sente actuellement que 12% de la population occidentale. Il s'agit l\u00e0 d'un probl\u00e8me qui se posera tr\u00e8s probablement \u00e0 la g\u00e9n\u00e9ration suivante. COVID peut encore changer les comportements, mais les mill\u00e9niaux et la g\u00e9n\u00e9ration Z chercheront des solutions diff\u00e9rentes. <a href=\"https:\/\/www.investglass.com\/fr\/6-bank-marketing-strategies-to-move-you-past-the-competition-in-2021\/\">campagnes de marketing<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-sharing-information\"><span class=\"ez-toc-section\" id=\"8_Sharing_information\"><\/span>8) Partage d'informations<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sultats montrent que si la g\u00e9n\u00e9ration Z est la prochaine g\u00e9n\u00e9ration \u00e0 avoir vu des \u00e9v\u00e9nements mondiaux importants, et si elle est tr\u00e8s ouverte au partage d'informations, ses attitudes \u00e0 l'\u00e9gard de la s\u00e9curit\u00e9 en ligne sont mitig\u00e9es. Pour les sp\u00e9cialistes du marketing qui s'interrogent sur la meilleure fa\u00e7on d'approcher les consommateurs de la g\u00e9n\u00e9ration Z, une chose semble certaine : Les adolescents ne se pr\u00e9occupent pas de la protection de la vie priv\u00e9e, mais ils devraient le faire car cela pourrait les affecter \u00e0 l'avenir de bien des fa\u00e7ons.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne s'agit pas d'une g\u00e9n\u00e9ration silencieuse, les g\u00e9n\u00e9rations diff\u00e8rent mais il n'y a pas de g\u00e9n\u00e9ration id\u00e9ale pour votre entreprise.... il est temps d'agir ! Les membres de la g\u00e9n\u00e9ration z anticiperont les difficult\u00e9s \u00e0 travailler avec les grandes entreprises et seront certainement plus attentifs aux dettes d'\u00e9tudes importantes.<a href=\"https:\/\/www.investglass.com\/fr\/jeunes-banquiers-nous-navons-pas-le-temps-pour-cela\/\"> Les employ\u00e9s de la g\u00e9n\u00e9ration Z consid\u00e8rent \u00e9galement leurs loisirs d'une mani\u00e8re diff\u00e9rente et vous le sentirez lorsque vous g\u00e9rerez votre entreprise.<\/a> les ressources humaines et la r\u00e9tention des talents. Les diff\u00e9rences entre les g\u00e9n\u00e9rations s'amenuisent. Investir dans vos outils num\u00e9riques n'est donc pas un pari g\u00e9n\u00e9rationnel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heureusement pour vous, InvestGlass a investi massivement dans les connaissances pour aider les entreprises comme la v\u00f4tre \u00e0 comprendre ce qu'il faut pour convertir ces consommateurs avec succ\u00e8s afin que votre entreprise puisse cro\u00eetre avec eux ! Avec des outils et des services con\u00e7us sp\u00e9cifiquement pour les GenZers et les mill\u00e9niaux, nous sommes convaincus que vous serez en mesure de r\u00e9pondre \u00e0 leurs demandes tout en maintenant une excellente exp\u00e9rience \u00e0 chaque \u00e9tape de l'entonnoir - tout cela sans vous ruiner. <a href=\"https:\/\/www.investglass.com\/fr\/6-bank-marketing-strategies-to-move-you-past-the-competition-in-2021\/\">budgets de marketing<\/a> ou l'embauche de nouveaux employ\u00e9s. \u00cates-vous pr\u00eats ?<\/p>","protected":false},"excerpt":{"rendered":"<p>Millennials have long been the focal point of marketing strategies due to their substantial purchasing power and technological proficiency. However, a new cohort, Generation Z individuals born between 1997 and 2012 is emerging as a significant consumer base. As of 2024, Generation Z comprises approximately\u00a028% of the global population, translating to over\u00a02.2 billion individuals worldwide\u00a0(Maverish). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[455,454],"class_list":["post-30443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-generation-z","tag-millennials"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Generation Z: How Millennials are different<\/title>\n<meta name=\"description\" content=\"Discover how Generation Z differs from millennials. Understand their values, behavior, and impact on the modern world.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/fr\/generation-z-les-differences-entre-les-milleniaux-et-ce-quil-faut-savoir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generation Z: How Millennials are different and what we should know?\" \/>\n<meta property=\"og:description\" content=\"Millennials have long been the focal point of marketing strategies due to their substantial purchasing power and technological proficiency. However, a new\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/fr\/generation-z-les-differences-entre-les-milleniaux-et-ce-quil-faut-savoir\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T11:16:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T05:19:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"G\u00e9n\u00e9ration Z : en quoi les Millennials sont diff\u00e9rents","description":"D\u00e9couvrez en quoi la g\u00e9n\u00e9ration Z diff\u00e8re des mill\u00e9niaux. Comprendre leurs valeurs, leur comportement et leur impact sur le monde moderne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/fr\/generation-z-les-differences-entre-les-milleniaux-et-ce-quil-faut-savoir\/","og_locale":"fr_FR","og_type":"article","og_title":"Generation Z: How Millennials are different and what we should know?","og_description":"Millennials have long been the focal point of marketing strategies due to their substantial purchasing power and technological proficiency. However, a new","og_url":"https:\/\/www.investglass.com\/fr\/generation-z-les-differences-entre-les-milleniaux-et-ce-quil-faut-savoir\/","og_site_name":"InvestGlass","article_published_time":"2021-07-08T11:16:56+00:00","article_modified_time":"2025-03-19T05:19:12+00:00","og_image":[{"width":800,"height":1200,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"\u00c9crit par":"InvestGlass","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"Generation Z: How Millennials are different and what we should know?","datePublished":"2021-07-08T11:16:56+00:00","dateModified":"2025-03-19T05:19:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/"},"wordCount":1125,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg","keywords":["Generation Z:","Millennials"],"articleSection":["Article"],"inLanguage":"fr-FR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/fr\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/","url":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/","name":"G\u00e9n\u00e9ration Z : en quoi les Millennials sont diff\u00e9rents","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg","datePublished":"2021-07-08T11:16:56+00:00","dateModified":"2025-03-19T05:19:12+00:00","description":"D\u00e9couvrez en quoi la g\u00e9n\u00e9ration Z diff\u00e8re des mill\u00e9niaux. Comprendre leurs valeurs, leur comportement et leur impact sur le monde moderne.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/07\/pltqjtofldw.jpg","width":800,"height":1200,"caption":"woman in white shirt wearing black and brown fedora hat"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"Generation Z: How Millennials are different and what we should know?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"Le CRM souverain suisse","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/fr\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.investglass.com\/generation-z-how-millenials-are-different-and-what-we-should-know\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts\/30443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/comments?post=30443"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/posts\/30443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/media\/30445"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/media?parent=30443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/categories?post=30443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/fr\/wp-json\/wp\/v2\/tags?post=30443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}