{"id":29441,"date":"2023-03-02T11:28:46","date_gmt":"2023-03-02T10:28:46","guid":{"rendered":"https:\/\/www.investglass.com\/?p=29441"},"modified":"2025-03-18T10:51:28","modified_gmt":"2025-03-18T09:51:28","slug":"como-elegir-un-crm-en-2023","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/es\/how-to-choose-a-crm-in-2023\/","title":{"rendered":"\u00bfC\u00f3mo elegir un CRM en 2023?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Elegir el CRMS adecuado para su empresa puede resultar dif\u00edcil. CRM significa Gesti\u00f3n de las Relaciones con los Clientes. Existen muchas opciones y no hay dos CRM iguales. Por eso es importante investigar antes de tomar una decisi\u00f3n. En esta entrada del blog, vamos a discutir qu\u00e9 factores debe considerar al tomar una decisi\u00f3n sobre qu\u00e9 CRM es mejor para usted y su negocio en 2023.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"225\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow-1024x225.png\" alt=\"Flujo de trabajo de InvestGlass\" class=\"wp-image-35830\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow-1024x225.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow-300x66.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow-768x168.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow-1536x337.png 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/03\/investglass-worflow.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Flujo de trabajo de InvestGlass<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_do_I_choose_a_small_business_CRM\"><\/span><strong>\u00bfC\u00f3mo elegir un CRM para peque\u00f1as empresas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para elegir un CRM hay que planificar la proporci\u00f3n <a href=\"https:\/\/www.investglass.com\/es\/analisis-exhaustivo-de-los-costes-de-las-soluciones-crm-in-situ\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2594\">coste<\/a> a los ingresos que ahorrar\u00e1 utilizando el CRM. Un buen CRM debe tener un precio asequible, ser f\u00e1cil de usar y ofrecer las funciones que necesita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es importante considerar qu\u00e9 tipo de <a href=\"https:\/\/www.investglass.com\/es\/el-papel-de-la-crm-movil-en-entornos-de-trabajo-remotos-el-futuro-del-trabajo\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2622\">CRM funcionar\u00e1<\/a> mejor para su empresa. Hay dos tipos principales:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- En las instalaciones <a href=\"https:\/\/www.investglass.com\/es\/crm-que-es-y-por-que-es-importante\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"815\">CRM significa<\/a> en su servidor, que es m\u00e1s caro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- El CRM basado en la nube (tambi\u00e9n conocido como off-premise) es m\u00e1s barato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los CRMS locales suelen costar menos que la nube.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces su CRM debe tener un buen <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/es\/herramientas-de-marketing\/\" target=\"_blank\" rel=\"noopener\" title=\"marketing por correo electr\u00f3nico\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"566\">marketing por correo electr\u00f3nico<\/a> herramientas. El marketing por correo electr\u00f3nico es una parte importante del marketing y debe tenerse en cuenta a la hora de tomar una decisi\u00f3n sobre CRM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si desea utilizar sus datos en otro software, aseg\u00farese de que el CRM puede exportar o importar sus datos a diferentes formatos, como CSV, por ejemplo. Esto se llama interoperabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los CRM tienen una versi\u00f3n de prueba gratuita y precios SAAS. Puede pagar por mes y por asiento de su CRM para aumentar el n\u00famero de asientos a medida que crece.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-do-small-businesses-keep-track-of-sales\"><span class=\"ez-toc-section\" id=\"How_do_small_businesses_keep_track_of_sales\"><\/span><strong>\u00bfC\u00f3mo controlan las ventas las peque\u00f1as empresas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Usted debe tener con cualquier CRM una peque\u00f1a curva de aprendizaje. Publicamos webinars y v\u00eddeos semanales y ayuda directa. Las peque\u00f1as empresas apreciar\u00e1n ver la previsi\u00f3n de ventas, el pipeline de ventas, el lead scoring sin programaci\u00f3n ni configuraciones complejas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El CRM para peque\u00f1as empresas deber\u00eda estar m\u00e1s o menos listo para funcionar en una hora. El equipo de ventas importar\u00e1 f\u00e1cilmente sus contactos con una soluci\u00f3n de arrastrar y soltar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COM puede conectarse a las llamadas telef\u00f3nicas y una conexi\u00f3n directa entre ambas soluciones evitar\u00e1 la doble introducci\u00f3n de datos. Empresas de todos los tama\u00f1os pueden conectarse a este sistema de llamadas. Le sugerimos que eche un vistazo a Aircall.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Disoluci\u00f3n con S pipeline management facilitar\u00e1 la lectura del proceso de ventas. El personal de marketing y ventas si tiene ambos apreciar\u00e1 que la interfaz de usuario es f\u00e1cil de usar. El especialista en marketing apreciar\u00e1 la campa\u00f1a de marketing en sustituci\u00f3n de herramientas de uso com\u00fan como Mailchimp, Freshworks CRM, Hubspot CRM, Zoho CRM o Pipedrive CRM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">InvestGlass est\u00e1 alojado en servidores suizos, lo que sin duda apreciar\u00e1 si se preocupa por la privacidad de sus datos y el alojamiento. El soporte al cliente tambi\u00e9n es importante y ofrecemos una versi\u00f3n premium de InvestGlass donde nuestro equipo dedicar\u00e1 el tiempo necesario para configurar su CRM y hacer que los propietarios de negocios conf\u00eden en la herramienta.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"627\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/investglass-welcome-dashboard-1-1024x627.png\" alt=\"InvestGlass, el CRM y PMS suizo\" class=\"wp-image-34178\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/investglass-welcome-dashboard-1-1024x627.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/investglass-welcome-dashboard-1-300x184.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/investglass-welcome-dashboard-1-768x470.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/08\/investglass-welcome-dashboard-1.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass, el CRM y PMS suizo<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"What_about_sales_workflow_automation\"><\/span><strong>\u00bfY la automatizaci\u00f3n del flujo de trabajo de ventas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si su peque\u00f1a empresa quiere escalar r\u00e1pidamente y su n\u00famero de usuarios es limitado, le sugerimos que eche un vistazo a nuestra herramienta de automatizaci\u00f3n. Estas herramientas est\u00e1n conectadas a Zapier, que es un puente para conectarse a m\u00e1s de 1000 aplicaciones basadas en la nube. Los empresarios sue\u00f1an, \u00bfverdad?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos sugerir, como un conservador de arte, qu\u00e9 aplicaciones m\u00f3viles se adaptar\u00e1n mejor a las necesidades de su empresa y qu\u00e9 datos de los clientes conectar\u00e1n con qu\u00e9 funciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No hay programaci\u00f3n para su marketing y servicio al cliente e InvestGlass har\u00e1 la \u201cfontaner\u00eda\u201d entre las aplicaciones basadas en la nube si es necesario. Si desea conectar Intercom, Docusign, Slack, incluso Whatsapp esto es posible. Los representantes de ventas progresar\u00e1n con nuevas necesidades, por lo que es importante conectar los nuevos ladrillos a las funciones CRM existentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que elija los ladrillos, crear\u00e1 en su CRM para peque\u00f1as empresas una automatizaci\u00f3n del flujo de trabajo de ventas \u00a1como una empresa Forbes 500! S\u00ed, las relaciones con los clientes con <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/es\/herramientas-de-automatizacion\/\" target=\"_blank\" rel=\"noopener\" title=\"inteligencia artificial\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"340\">inteligencia artificial<\/a> son accesibles para las peque\u00f1as empresas. Por ejemplo, bas\u00e1ndose en los datos de sus clientes recopilados a partir de la generaci\u00f3n de leads, la IA puede filtrar los leads y dirigirlos a las ventas o servicios adecuados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si los flujos de ventas se ralentizan demasiado, el CRM enviar\u00e1 un aviso a los representantes de ventas para que aceleren la gesti\u00f3n de los proyectos. Se acab\u00f3 el estr\u00e9s para los empresarios y los equipos de ventas, porque la m\u00e1quina automatiza las ventas CON usted.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-pipeline-revenue.jpeg\" alt=\"Tuber\u00edas InvestGlass\" class=\"wp-image-32685\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-pipeline-revenue.jpeg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-pipeline-revenue-300x225.jpeg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/06\/investglass-pipeline-revenue-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Tuber\u00edas InvestGlass<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Las campa\u00f1as de marketing tambi\u00e9n son una herramienta importante a medida que se crece. Cuando una campa\u00f1a no se abre correctamente, el CRM puede activar otra secuencia para asegurarse de que su equipo de ventas de marketing realiza un seguimiento activo de los clientes. Ahora se merece el mejor CRM posible y&nbsp;<a href=\"https:\/\/www.investglass.com\/es\/puede-un-crm-sustituir-al-software-de-automatizacion-de-marketing\/\">automatizaci\u00f3n del marketing<\/a>&nbsp;es f\u00e1cil de configurar. Los equipos de ventas y marketing colaborar\u00e1n porque es muy F\u00c1CIL.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Choosing the right CRMS for your business can be difficult. CRM means Customer Relationship Management. There are a lot of options out there, and no two CRMs are alike. That is why it\u2019s important to do your research before making any decisions. In this blog post, we will discuss what factors you should consider when [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[418],"class_list":["post-29441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-crm-trends"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How to choose a CRM in 2023? | InvestGlass<\/title>\n<meta name=\"description\" content=\"Find the best CRM for your business in 2023. Compare features, pricing, and benefits to make the right choice.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/es\/como-elegir-un-crm-en-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to choose a CRM in 2023?\" \/>\n<meta property=\"og:description\" content=\"Choosing the right CRMS for your business can be difficult. CRM means Customer Relationship Management. There are a lot of options out there, and no two\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/es\/como-elegir-un-crm-en-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T10:28:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T09:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo elegir un CRM en 2023? | InvestGlass","description":"Encuentre el mejor CRM para su empresa en 2023. Compare funciones, precios y ventajas para tomar la decisi\u00f3n correcta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/es\/como-elegir-un-crm-en-2023\/","og_locale":"es_ES","og_type":"article","og_title":"How to choose a CRM in 2023?","og_description":"Choosing the right CRMS for your business can be difficult. CRM means Customer Relationship Management. There are a lot of options out there, and no two","og_url":"https:\/\/www.investglass.com\/es\/como-elegir-un-crm-en-2023\/","og_site_name":"InvestGlass","article_published_time":"2023-03-02T10:28:46+00:00","article_modified_time":"2025-03-18T09:51:28+00:00","og_image":[{"width":960,"height":1200,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Escrito por":"InvestGlass","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"How to choose a CRM in 2023?","datePublished":"2023-03-02T10:28:46+00:00","dateModified":"2025-03-18T09:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/"},"wordCount":781,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg","keywords":["CRM trends"],"articleSection":["Article"],"inLanguage":"es","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/es\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/","url":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/","name":"\u00bfC\u00f3mo elegir un CRM en 2023? | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg","datePublished":"2023-03-02T10:28:46+00:00","dateModified":"2025-03-18T09:51:28+00:00","description":"Encuentre el mejor CRM para su empresa en 2023. Compare funciones, precios y ventajas para tomar la decisi\u00f3n correcta.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/e4kkgi4ogau.jpg","width":960,"height":1200,"caption":"round silver-colored smartwatch bokeh photography"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"How to choose a CRM in 2023?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"El Soberano Suizo CRM","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/es\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.investglass.com\/how-to-choose-a-crm-in-2023\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts\/29441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/comments?post=29441"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts\/29441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/media\/29442"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/media?parent=29441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/categories?post=29441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/tags?post=29441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}