{"id":29038,"date":"2021-05-16T18:04:05","date_gmt":"2021-05-16T16:04:05","guid":{"rendered":"https:\/\/www.investglass.com\/?p=29038"},"modified":"2025-11-06T20:02:57","modified_gmt":"2025-11-06T19:02:57","slug":"como-digitalizar-eficazmente-su-proceso-de-incorporacion","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/es\/how-to-efficiently-digitalize-your-onboarding-process\/","title":{"rendered":"\u00bfC\u00f3mo digitalizar eficazmente su proceso de incorporaci\u00f3n?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Todos los sectores utilizan ampliamente el t\u00e9rmino \u201cDigital onboarding\u201d; sin embargo, su significado var\u00eda. En la banca y los servicios financieros, el onboarding digital significa la creaci\u00f3n de cuentas bancarias o registros similares en l\u00ednea. Centr\u00e1ndonos en CRM, el significado se acerca al de las empresas que utilizan el sistema CRM y sus herramientas de onboarding. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2016, la FINMA permite la incorporaci\u00f3n de clientes de forma puramente digital. Las soluciones de verificaci\u00f3n de la identidad han hecho que el proceso de incorporaci\u00f3n sea seguro y que la identidad del cliente pueda verificarse mediante tecnolog\u00eda de aprendizaje autom\u00e1tico.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"geodir-embed-container\"><iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 es la digitalizaci\u00f3n de documentos?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/es\/incorporacion-digital\/\"   title=\"Incorporaci\u00f3n digital\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"116\">Incorporaci\u00f3n digital<\/a> superar\u00e1 a medio y largo plazo a los formularios en papel y a la recopilaci\u00f3n tradicional de datos KYC. Esta digitalizaci\u00f3n permite reducir la mano de obra y los costes para las empresas, especialmente en el sector bancario y los flujos de trabajo de apertura de cuentas bancarias. Una vez incorporados, los clientes son f\u00e1cilmente gestionables y se convierten en usuarios de la interfaz CRM. Podemos compartir la provisi\u00f3n de un portal de clientes, la remediaci\u00f3n de KYC o las necesidades complementarias de onboarding, como la carga de archivos (DNI, comprobante de domicilio, etc.) a trav\u00e9s de la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante el CRM, los empleados pueden adaptar la soluci\u00f3n de incorporaci\u00f3n e influir en el proceso de incorporaci\u00f3n. La incorporaci\u00f3n de empleados tambi\u00e9n puede mejorar las capacidades de la empresa al permitir la flexibilidad del equipo de recursos humanos con una gesti\u00f3n eficiente del talento en las contrataciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-digital-onboarding-financial-services-with-investglass\"><span class=\"ez-toc-section\" id=\"Digital_Onboarding_%E2%80%93_Financial_Services_with_InvestGlass\"><\/span>Onboarding digital - Servicios financieros con InvestGlass<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En InvestGlass, ofrecemos una soluci\u00f3n CRM todo en uno que incluye un proceso de incorporaci\u00f3n completo. Nuestros clientes pueden elegir entre la incorporaci\u00f3n digital completa, la incorporaci\u00f3n en papel completa o una combinaci\u00f3n de ambas, aunque el uso del papel aumenta la carga de trabajo manual. La incorporaci\u00f3n digital puede dividirse en tres etapas principales. En primer lugar, el cliente debe rellenar uno o varios formularios para introducir correctamente sus datos en la m\u00e1quina. En segundo lugar, la puesta en marcha de procesos de aprobaci\u00f3n y verificaciones de identidad. Por \u00faltimo, es posible que haya que realizar correcciones KYC en una fase posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La invitaci\u00f3n a la recogida de datos puede adoptar diversas formas en funci\u00f3n de la experiencia de usuario deseada. <a href=\"https:\/\/www.investglass.com\/es\/cosas-que-debe-saber-antes-de-poner-en-marcha-su-banco-digital\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"447\">Los bancos necesitan digitalizarse<\/a> sus formularios de incorporaci\u00f3n, que luego pueden enviarse a clientes potenciales concretos. Puede enviar estos formularios por correo electr\u00f3nico o incrustar formularios de firma sencillos en su sitio web. Dependiendo de la pol\u00edtica de privacidad de la organizaci\u00f3n, es posible que los clientes potenciales ya dispongan de un portal de clientes, en cuyo caso los formularios pueden compartirse directamente a trav\u00e9s del portal. Los clientes potenciales s\u00f3lo tienen que rellenar la informaci\u00f3n y los archivos necesarios a trav\u00e9s de los formularios y usted recibe una notificaci\u00f3n una vez que han terminado su trabajo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1024x705.png\" alt=\"\" class=\"wp-image-32243\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1024x705.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-300x207.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-768x529.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass-1536x1058.png 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/05\/campaign-investglass.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass Herramienta de campa\u00f1a creada para la remediaci\u00f3n KYC y la incorporaci\u00f3n digital<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El onboarding digital pretende simplificar la adopci\u00f3n por parte de clientes y consumidores de la decisi\u00f3n de aceptar o rechazar a dicho cliente potencial. Las empresas tambi\u00e9n quieren verificar la identidad de los prospectos y comprobar sus nombres en las listas AML y de alerta. Para verificar a los individuos y a las personas que rellenan los formularios, se puede utilizar una gran variedad de socios, desde comprobaciones AML hasta verificaci\u00f3n de identidad por reconocimiento facial. Es posible automatizar estas comprobaciones o lanzarlas manualmente en funci\u00f3n de sus necesidades. Una vez que un cliente potencial est\u00e1 en una categor\u00eda, por ejemplo, riesgo bajo, riesgo medio o individuo PEP, puede lanzar (de nuevo autom\u00e1ticamente o no) un <a class=\"wpil_keyword_link\" href=\"https:\/\/www.investglass.com\/es\/herramientas-de-venta\/\" target=\"_blank\" rel=\"noopener\" title=\"proceso de aprobaci\u00f3n\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"734\">proceso de aprobaci\u00f3n<\/a>. Los procesos de aprobaci\u00f3n permiten aceptar o rechazar clientes potenciales en funci\u00f3n de sus respuestas, nivel de riesgo, etc. Usted establece las reglas del juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez aceptado un cliente potencial, puede crear un acceso al portal del cliente, iniciar la comunicaci\u00f3n, compartir documentos, crear propuestas de inversi\u00f3n y utilizar todas las funciones y productos de la soluci\u00f3n para crear relaciones s\u00f3lidas y duraderas. Y lo que es m\u00e1s importante, puede crear <a href=\"https:\/\/www.investglass.com\/es\/automatizacion-robotica-de-procesos-rpa-como-puede-transformar-su-empresa\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"271\">automatizar y desarrollar f\u00e1cilmente los procesos de correcci\u00f3n KYC<\/a>. Por ejemplo, puede que desee establecer una comprobaci\u00f3n de remediaci\u00f3n KYC si un usuario cambia su direcci\u00f3n, nacionalidad o estado civil. La remediaci\u00f3n KYC representa la comprobaci\u00f3n de la informaci\u00f3n de los clientes. Normalmente, se realiza de forma puntual o en eventos especiales. A trav\u00e9s de InvestGlass, puede notificar la remediaci\u00f3n en cualquier dispositivo y compartir formularios de remediaci\u00f3n por correo electr\u00f3nico o portal de clientes. Obviamente, las formas tradicionales, como las llamadas telef\u00f3nicas o las reuniones en persona, siguen siendo factibles, \u00a1pero queremos pasar a lo digital!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1024x683.jpg\" alt=\"persona caminando con un bolso de cuero marr\u00f3n en la mano\" class=\"wp-image-29040\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1024x683.jpg 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-300x200.jpg 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-768x512.jpg 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye-1536x1024.jpg 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-do-not-forget-the-client-is-human\"><span class=\"ez-toc-section\" id=\"Do_not_forget_the_client_is_human\"><\/span>No olvide que el cliente es humano.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Centr\u00e9monos en los trucos y consejos a la hora de incorporar clientes potenciales. Tanto si es un <a href=\"https:\/\/www.investglass.com\/es\/principales-retos-de-la-adopcion-de-ai-en-la-banca-y-como-superarlos\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2273\">banco challenger<\/a> o una ya establecida, podr\u00edan despertar su inter\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n lo es todo. Al configurar los formularios y el proceso de incorporaci\u00f3n, aseg\u00farate de que el flujo de trabajo y cada paso sean claros y completos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sea sencillo y r\u00e1pido. No debe pedir a un cliente potencial que rellene un formulario durante m\u00e1s de 10 minutos.<br>Divida el proceso de incorporaci\u00f3n. Para mantener el compromiso de sus clientes potenciales, distribuya el proceso en varios pasos o etapas.<br>Establezca expectativas y objetivos claros. Esto le ayudar\u00e1 a evaluar las m\u00e9tricas y la calidad de su incorporaci\u00f3n. Esto le ayudar\u00e1 a maximizar la captaci\u00f3n de clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obtenga opiniones con regularidad. Permita que sus prospectos y clientes le env\u00eden sus comentarios para mejorar sus flujos de trabajo. Adopte la incorporaci\u00f3n digital y espere un aumento de 80% en sus tasas de retenci\u00f3n. Sin embargo, vigile de cerca su proceso, ya que 60% de los clientes abandonaron el onboarding digital el a\u00f1o pasado por m\u00faltiples razones, como la complejidad, la duraci\u00f3n, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.investglass.com\/es\/empezar-gratis\/\">Empecemos con la prueba gratuita de InvestGlass<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>All sectors widely use the term &#8220;Digital onboarding&#8221;; however, its meaning varies. In banking and financial services, digital onboarding means the creation of banking accounts or similar records online. Focusing on CRM, the meaning is close to one of the businesses using the CRM system and its onboarding tools. Since 2016, FINMA has enabled customer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[45],"class_list":["post-29038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-digital-onboarding"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How to Efficiently Digitalize your Onboarding Process? | InvestGlass<\/title>\n<meta name=\"description\" content=\"Learn how to digitalize your onboarding process to reduce manual work, improve compliance, and deliver a seamless client experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/es\/como-digitalizar-eficazmente-su-proceso-de-incorporacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Efficiently Digitalize your Onboarding Process?\" \/>\n<meta property=\"og:description\" content=\"All sectors widely use the term &quot;Digital onboarding&quot;; however, its meaning varies. In banking and financial services, digital onboarding means the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/es\/como-digitalizar-eficazmente-su-proceso-de-incorporacion\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-16T16:04:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"2125\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2021-05-16T16:04:05+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo digitalizar eficazmente su proceso de incorporaci\u00f3n? | InvestGlass","description":"Aprenda a digitalizar su proceso de incorporaci\u00f3n para reducir el trabajo manual, mejorar el cumplimiento y ofrecer una experiencia de cliente fluida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/es\/como-digitalizar-eficazmente-su-proceso-de-incorporacion\/","og_locale":"es_ES","og_type":"article","og_title":"How to Efficiently Digitalize your Onboarding Process?","og_description":"All sectors widely use the term \"Digital onboarding\"; however, its meaning varies. In banking and financial services, digital onboarding means the","og_url":"https:\/\/www.investglass.com\/es\/como-digitalizar-eficazmente-su-proceso-de-incorporacion\/","og_site_name":"InvestGlass","article_published_time":"2021-05-16T16:04:05+00:00","article_modified_time":"2025-11-06T19:02:57+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","type":"image\/jpeg"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Escrito por":"InvestGlass","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"How to Efficiently Digitalize your Onboarding Process?","datePublished":"2021-05-16T16:04:05+00:00","dateModified":"2025-11-06T19:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"},"wordCount":831,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","keywords":["Digital onboarding"],"articleSection":["Article"],"inLanguage":"es","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/es\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/","url":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/","name":"\u00bfC\u00f3mo digitalizar eficazmente su proceso de incorporaci\u00f3n? | InvestGlass","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","datePublished":"2021-05-16T16:04:05+00:00","dateModified":"2025-11-06T19:02:57+00:00","description":"Aprenda a digitalizar su proceso de incorporaci\u00f3n para reducir el trabajo manual, mejorar el cumplimiento y ofrecer una experiencia de cliente fluida.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2021\/05\/6dw3xyqvcye.jpg","width":1600,"height":1067,"caption":"person walking holding brown leather bag"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"How to Efficiently Digitalize your Onboarding Process?"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"El Soberano Suizo CRM","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/es\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.investglass.com\/hi\/%e0%a4%85%e0%a4%aa%e0%a4%a8%e0%a5%80-%e0%a4%91%e0%a4%a8%e0%a4%ac%e0%a5%8b%e0%a4%b0%e0%a5%8d%e0%a4%a1%e0%a4%bf%e0%a4%82%e0%a4%97-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%8d%e0%a4%b0%e0%a4%bf%e0%a4%af\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]},"og_video":"https:\/\/www.youtube.com\/embed\/n6F4L46AfBI","og_video_type":"text\/html","og_video_duration":"2125","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2021-05-16T16:04:05+00:00","ya_ovs_allow_embed":"true"},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts\/29038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/comments?post=29038"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/posts\/29038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/media\/29040"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/media?parent=29038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/categories?post=29038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/es\/wp-json\/wp\/v2\/tags?post=29038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}