{"id":28957,"date":"2021-05-16T00:22:27","date_gmt":"2021-05-15T22:22:27","guid":{"rendered":"https:\/\/investglass.com\/?p=28957"},"modified":"2026-06-25T13:20:01","modified_gmt":"2026-06-25T11:20:01","slug":"ein-leitfaden-was-ihr-mitarbeiterportal-enthalten-sollte-worter","status":"publish","type":"post","link":"https:\/\/www.investglass.com\/de\/a-guide-to-what-your-employee-portal-should-include-words\/","title":{"rendered":"Ein Leitfaden f\u00fcr das, was Ihr Mitarbeiterportal enthalten sollte"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ein Mitarbeiterportal ist das R\u00fcckgrat der Personalabteilung eines Unternehmens. Es kann dazu beitragen, Ihre Arbeitsabl\u00e4ufe zu straffen, die Effizienz zu steigern und den Mitarbeitern Ressourcen zur Verf\u00fcgung zu stellen. Es ist jedoch wichtig, dass Sie die Grundlagen nicht \u00fcbersehen. Im Folgenden finden Sie f\u00fcnf Dinge, die ein Mitarbeiterportal enthalten sollte:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-a-help-desk-for-quick-questions-on-policies-and-procedures\"><span class=\"ez-toc-section\" id=\"1_A_help_desk_for_quick_questions_on_policies_and_procedures\"><\/span>1) Ein Helpdesk f\u00fcr schnelle Fragen zu Politik und Verfahren<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">erstellen. <a href=\"https:\/\/www.investglass.com\/de\/rettet-die-welt-sagt-nein-zum-papier-onboarding\/\">neue Dokumente und Formulare<\/a> je nach Bedarf, ohne mehrere Prozesse zu durchlaufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f6ffentlichen Sie relevante Mitteilungen f\u00fcr die Mitarbeiter im Portal, damit alle Mitarbeiter darauf zugreifen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Machen Sie Ihren Helpdesk rund um die Uhr \u00fcber Live-Chat oder Telefonanrufe mit Mitarbeitern, die Hilfe ben\u00f6tigen, erreichbar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leistungen und Urlaub: Das Portal sollte Informationen \u00fcber Sozialleistungen und Urlaub enthalten. Auf diese Weise k\u00f6nnen die Mitarbeiter die Optionen sehen, die f\u00fcr sie am besten geeignet sind. Dazu geh\u00f6ren die folgenden Themen: Krankenversicherung, Altersvorsorge, Studienbeihilfeprogramme und Verf\u00fcgbarkeit von Urlaubs- und Krankheitszeiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-leave-tracking-with-approval-workflow\"><span class=\"ez-toc-section\" id=\"2_Leave_tracking_with_approval_workflow\"><\/span>2) Urlaubsverfolgung mit Genehmigungsworkflow<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach der Anmeldeseite sollten Ihre Mitarbeiter Zugang zu einem Kalender mit allen Terminen haben, die sie frei nehmen k\u00f6nnen. Das aktuelle Datum sollte hervorgehoben sein. Wenn Sie auf einen anderen Tag klicken, \u00f6ffnet sich ein Fenster mit allen freien Tagen f\u00fcr diesen Monat, einschlie\u00dflich Urlaubs- und Krankheitszeiten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Mitarbeiterportal sollte auch einen Genehmigungs-Workflow enthalten, um Genehmigungen durch Ihr Helpdesk-System zu verfolgen, damit Sie Genehmigungen durch einzelne Mitarbeiter oder Gruppen von Mitarbeitern besser verwalten k\u00f6nnen. Wenn ein Mitarbeiter mehr als drei aufeinanderfolgende freie Tage im Voraus beantragt, l\u00f6st dies eine automatische Benachrichtigung der Personalabteilung aus, die den Antrag genehmigt; wird er abgelehnt, m\u00fcssen vor der Genehmigung m\u00f6glicherweise weitere Ma\u00dfnahmen ergriffen werden, z. B. das Einholen von Informationen \u00fcber den Grund der Abwesenheit (z. B. ein \u00e4rztliches Attest).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da InvestGlass mit Finanzintermedi\u00e4ren arbeitet, haben wir <a href=\"https:\/\/www.investglass.com\/de\/wie-sie-ihren-reiseantragsprozess-automatisieren-konnen\/\">einen Reiseantrag erstellen<\/a> Widget, das alle Kontakte einfriert, die Sie w\u00e4hrend der Reise nicht besuchen werden. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"938\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate-1024x938.png\" alt=\"InvestGlass Anlegerportal\" class=\"wp-image-40145\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate-1024x938.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate-300x275.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate-768x703.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate-1536x1407.png 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2024\/05\/InvestGlass-portal-realestate.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass Anlegerportal<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-expense-reporting-forms-so-you-know-what-kind-of-money-is-being-spent-at-corporate-events\"><span class=\"ez-toc-section\" id=\"3_Expense_reporting_forms_so_you_know_what_kind_of_money_is_being_spent_at_corporate_events\"><\/span>3) Formulare f\u00fcr Ausgabenberichte, damit Sie wissen, wie viel Geld bei Firmenveranstaltungen ausgegeben wird<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein direkter Link zur Rechnungserstellung erleichtert die Erstellung einer Spesenabrechnung. Alle Ausgaben und Rechnungen k\u00f6nnen in das System hochgeladen werden, und alle Mitarbeiter haben Zugriff auf diese Informationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erstellen Sie Ihre eigenen Spesenabrechnungsformulare, damit Sie wissen, wie viel Geld bei Firmenveranstaltungen ausgegeben wird. Oder zumindest, wohin das Geld geflossen ist!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es Probleme mit Berichten oder Rechnungen gibt, senden Sie diese \u00fcber eine Helpdesk-Anfrage, die <a href=\"https:\/\/www.investglass.com\/de\/automatisierungstools\/\">automatisch<\/a> eine E-Mail-Benachrichtigung von der Personalabteilung ausl\u00f6sen; wenn vor der Genehmigung weitere Ma\u00dfnahmen erforderlich sind, z. B. die Einholung weiterer Informationen dar\u00fcber, warum der Antragsteller m\u00f6glicherweise nicht f\u00fcr die Genehmigung von Urlaubsantr\u00e4gen zur Verf\u00fcgung steht, m\u00fcssen diese Ma\u00dfnahmen zuerst erfolgen. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-an-organizational-chart-so-everyone-knows-who-reports-to-whom\"><span class=\"ez-toc-section\" id=\"4_An_organizational_chart_so_everyone_knows_who_reports_to_whom\"><\/span>4) Ein Organigramm, damit jeder wei\u00df, wer wem unterstellt ist<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Termin- und Schichtverwaltung sollte pro Gruppe sichtbar sein und die Beitr\u00e4ge sollten nach Datum abgelegt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies hilft bei der Einteilung der Mitarbeiter f\u00fcr Projekte und stellt sicher, dass jeder wei\u00df, wer sein Vorgesetzter ist. Die Mitarbeiter wissen, an wen sie sich wenden k\u00f6nnen, wenn etwas passiert, das weitere Unterst\u00fctzung oder Kl\u00e4rung erfordert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Art und Weise, wie Beitr\u00e4ge geplant werden sollten, erleichtert es den Vorgesetzten auch, zu sehen, welche Zeit ein Mitarbeiter genommen hat und wann er wieder verf\u00fcgbar ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Organigramm erleichtert es den Mitarbeitern der Personalabteilung, all diese Informationen auf einen Blick zu finden - egal, ob eine Person f\u00fcr die Social-Media-Konten Ihres Unternehmens zust\u00e4ndig ist oder ob f\u00fcnf Personen in verschiedenen Schichten arbeiten, alles ist immer noch leicht zu finden, ohne dass zus\u00e4tzliche Hilfe von anderen Abteilungen, wie z. B. der IT-Abteilung, ben\u00f6tigt wird, um die Informationen abzurufen, weil die Abl\u00e4ufe in diesem Bereich unklar sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-internal-messaging-system-for-instant-communication\"><span class=\"ez-toc-section\" id=\"5_Internal_messaging_system_for_instant_communication\"><\/span>5) Internes Nachrichtensystem f\u00fcr Sofortkommunikation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die gesamte Kommunikation kann \u00fcber eine <a href=\"https:\/\/www.investglass.com\/de\/marketinginstrumente\/\">Chat-Kommunikationsmittel<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies kann dazu beitragen, Beziehungen zu denjenigen aufzubauen, die vielleicht nicht die Zeit haben, regelm\u00e4\u00dfig E-Mails zu bearbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Chatsystem macht auch Telefonanrufe \u00fcberfl\u00fcssig, die oft unbequemer sind als Chats, da sie viel von der kostbaren Zeit des Gespr\u00e4chspartners in Anspruch nehmen. Au\u00dferdem gibt es keine Garantie, dass der Gespr\u00e4chspartner gerade verf\u00fcgbar ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diejenigen, die lieber sprechen, k\u00f6nnen stattdessen Sprach- oder Videoanrufe nutzen, um ihren Standpunkt darzulegen, was es f\u00fcr alle Beteiligten noch einfacher macht.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"606\" src=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1-1024x606.png\" alt=\"\" class=\"wp-image-31265\" srcset=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1-1024x606.png 1024w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1-300x177.png 300w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1-768x454.png 768w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1-1536x908.png 1536w, https:\/\/www.investglass.com\/wp-content\/uploads\/2022\/02\/investglass-live-customer-chat-1.png 1806w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">InvestGlass Live-Kunden-Chat<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Interne Nachrichtensysteme eignen sich hervorragend, wenn Sie m\u00f6chten, dass Ihre Mitarbeiter aus der Ferne arbeiten - sei es in einem anderen Bundesland oder in einem anderen Land -, da diese Kommunikation sofort erfolgt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Aufgabe kann \u00fcber ein einfaches InvestGlass-Tool verteilt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viele dieser Tools sind kostenlos, und einige lassen sich an die Bed\u00fcrfnisse Ihres Unternehmens anpassen. Ganz gleich, ob Sie einen Helpdesk einrichten oder einfach nur Formulare zum Ausf\u00fcllen ben\u00f6tigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">InvestGlass wurde mit Blick auf die Benutzerfreundlichkeit entwickelt, damit die Mitarbeiter schnell und einfach durch das Portal navigieren k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was sollte ein Mitarbeiterportal beinhalten? Auf diese Frage gibt es keine einheitliche Antwort, da die Bed\u00fcrfnisse der Mitarbeiter in jedem Unternehmen unterschiedlich sind. Viele moderne Portale verf\u00fcgen heute \u00fcber eine Vielzahl hilfreicher Funktionen, die die Kommunikation aus der Ferne einfacher machen als je zuvor. Interne Nachrichtensysteme wie Skype erm\u00f6glichen es Mitarbeitern, die an einem beliebigen Ort der Welt arbeiten, problemlos mit anderen Mitarbeitern zu kommunizieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-the-next-employee-portal-for-2021\"><span class=\"ez-toc-section\" id=\"What_is_the_next_employee_portal_for_2021\"><\/span>Was ist das n\u00e4chste Mitarbeiterportal f\u00fcr 2021?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Laut einer\u00a0<em>Gartner<\/em>\u00a0Bericht, \u00fcber\u00a0<strong>85% von Unternehmen<\/strong>\u00a0haben Mitarbeiterportale implementiert oder sind dabei, diese zu aktualisieren, um die digitale Arbeitsumgebung zu verbessern. Plattformen wie\u00a0<em>InvestGlass<\/em>\u00a0erm\u00f6glichen es Unternehmen, ihre Benutzeroberfl\u00e4che an das Corporate Branding anzupassen und Mitarbeiterdaten, Gehaltsabrechnungen, Urlaubsregelungen und die interne Kommunikation effizient zu verwalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dem InvestGlass-Portal k\u00f6nnen Sie sich ganz einfach auf Ihre Unternehmensfarben einstellen und Widgets ausw\u00e4hlen, die Sie f\u00fcr den Registrierungsprozess, die Verwaltung von Benutzernamen, die Gehaltsabrechnung, die Urlaubsverwaltung, Ihre Unternehmensnachrichten, die Verwaltung von Karrierem\u00f6glichkeiten und die Zusammenfassung von Fragen in einer FAQ ben\u00f6tigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr Portal repr\u00e4sentiert Ihren Unternehmensgeist! Es ist die Familie!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.investglass.com\/de\/kostenlos-loslegen\/\">Starten Sie noch heute mit Ihrem kostenlosen InvestGlass-Test<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Frequently_Asked_Questions\"><\/span>H\u00e4ufig gestellte Fragen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Was ist ein Mitarbeiterportal?<\/strong><br>Ein Mitarbeiterportal ist ein zentraler Knotenpunkt, \u00fcber den Mitarbeiter auf HR-Ressourcen, Richtlinien und Tools zugreifen k\u00f6nnen. InvestGlass bietet ein vollst\u00e4ndig anpassbares Portal, das mit dem Branding Ihres Unternehmens \u00fcbereinstimmt und die internen Arbeitsabl\u00e4ufe rationalisiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Warum sollte ein Unternehmen ein Mitarbeiterportal einrichten?<\/strong><br>Mitarbeiterportale sparen Zeit, reduzieren den Papierkram und verbessern die Kommunikation. Mit InvestGlass k\u00f6nnen Unternehmen Urlaubsantr\u00e4ge, Ausgabengenehmigungen und Onboarding-Prozesse automatisieren und so die Effizienz steigern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Welche HR-Funktionen sollte ein Mitarbeiterportal enthalten?<\/strong><br>Zu den wesentlichen Funktionen geh\u00f6ren Helpdesks, Urlaubsverfolgung, Informationen \u00fcber Sozialleistungen und Ausgabenberichte. InvestGlass bietet all diese Funktionen und zus\u00e4tzlich auf Ihr Unternehmen zugeschnittene Widgets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Wie vereinfacht InvestGlass die Urlaubsverfolgung?<\/strong><br>Mitarbeiter k\u00f6nnen \u00fcber einen integrierten Kalender Freizeit beantragen. InvestGlass automatisiert Genehmigungen, benachrichtigt Manager und enth\u00e4lt sogar ein Widget f\u00fcr Reiseantr\u00e4ge f\u00fcr Finanzvermittler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. Kann ein Mitarbeiterportal die Spesenabrechnung \u00fcbernehmen?<\/strong><br>Ja. InvestGlass erm\u00f6glicht es den Mitarbeitern, Ausgaben und Rechnungen direkt hochzuladen, w\u00e4hrend die Manager die Genehmigungen in Echtzeit verfolgen und so f\u00fcr Transparenz und Kontrolle sorgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6. Warum ist ein Organigramm wichtig?<\/strong><br>Es zeigt die Berichtslinien und hilft bei der Zeitplanung und Kommunikation. InvestGlass macht Diagramme interaktiv und mit Mitarbeiterprofilen verkn\u00fcpft, was die Sichtbarkeit verbessert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7. Wie verbessert die interne Nachrichten\u00fcbermittlung die Zusammenarbeit?<\/strong><br>Messaging-Tools erm\u00f6glichen eine schnelle, sofortige Kommunikation zwischen Teams. InvestGlass integriert Live-Chat, Sprach- und Videofunktionen f\u00fcr Remote- und Hybrid-Teams.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8. Kann InvestGlass die Verwaltung von Sozialleistungen unterst\u00fctzen?<\/strong><br>Ja. Die Portale von InvestGlass zentralisieren die Krankenversicherungs-, Renten- und Urlaubsrichtlinien und erm\u00f6glichen den Mitarbeitern jederzeit einen einfachen Zugriff auf ihre Leistungsinformationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9. Wie anpassbar ist das InvestGlass-Mitarbeiterportal?<\/strong><br>InvestGlass erm\u00f6glicht ein vollst\u00e4ndiges Branding mit Unternehmensfarben und l\u00e4sst Sie aus einer breiten Palette von Widgets w\u00e4hlen, von Gehaltsabrechnungen bis hin zu Karriereseiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10. Warum InvestGlass als Mitarbeiterportal w\u00e4hlen?<\/strong><br>InvestGlass wird in der Schweiz gehostet, ist sicher und auf Benutzerfreundlichkeit ausgelegt. Es hilft HR-Teams, Zeit zu sparen, verbessert das Engagement der Mitarbeiter und schafft ein Portal, das Ihre Unternehmenskultur widerspiegelt.<\/p>","protected":false},"excerpt":{"rendered":"<p>An employee portal is the backbone of a company&#8217;s HR department. It can help streamline your workflows, create efficiencies, and provide resources to employees. However, it&#8217;s important not to overlook the basics. The following are five things that an employee portal should include: 1) A help desk for quick questions on policies and procedures Create [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[19,33],"class_list":["post-28957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-crm","tag-internal-messaging-systems"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>What Your Employee Portal Should Include<\/title>\n<meta name=\"description\" content=\"Learn the must-have features for an effective employee portal that boosts communication, engagement, and productivity in your organization.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investglass.com\/de\/ein-leitfaden-was-ihr-mitarbeiterportal-enthalten-sollte-worter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Guide to What Your Employee Portal Should Include\" \/>\n<meta property=\"og:description\" content=\"An employee portal is the backbone of a company&#039;s HR department. It can help streamline your workflows, create efficiencies, and provide resources to\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investglass.com\/de\/ein-leitfaden-was-ihr-mitarbeiterportal-enthalten-sollte-worter\/\" \/>\n<meta property=\"og:site_name\" content=\"InvestGlass\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-15T22:22:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T11:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1402\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"InvestGlass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@investglass\" \/>\n<meta name=\"twitter:site\" content=\"@investglass\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"InvestGlass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was Ihr Mitarbeiterportal enthalten sollte","description":"Erfahren Sie, welche Funktionen ein effektives Mitarbeiterportal haben muss, um die Kommunikation, das Engagement und die Produktivit\u00e4t in Ihrem Unternehmen zu f\u00f6rdern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investglass.com\/de\/ein-leitfaden-was-ihr-mitarbeiterportal-enthalten-sollte-worter\/","og_locale":"de_DE","og_type":"article","og_title":"A Guide to What Your Employee Portal Should Include","og_description":"An employee portal is the backbone of a company's HR department. It can help streamline your workflows, create efficiencies, and provide resources to","og_url":"https:\/\/www.investglass.com\/de\/ein-leitfaden-was-ihr-mitarbeiterportal-enthalten-sollte-worter\/","og_site_name":"InvestGlass","article_published_time":"2021-05-15T22:22:27+00:00","article_modified_time":"2026-06-25T11:20:01+00:00","og_image":[{"width":2048,"height":1402,"url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png","type":"image\/png"}],"author":"InvestGlass","twitter_card":"summary_large_image","twitter_creator":"@investglass","twitter_site":"@investglass","twitter_misc":{"Verfasst von":"InvestGlass","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#article","isPartOf":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/"},"author":{"name":"InvestGlass","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24"},"headline":"A Guide to What Your Employee Portal Should Include","datePublished":"2021-05-15T22:22:27+00:00","dateModified":"2026-06-25T11:20:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/"},"wordCount":1281,"publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"image":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png","keywords":["CRM","Internal messaging systems"],"articleSection":["Article"],"inLanguage":"de","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.investglass.com\/de\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/","url":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/","name":"Was Ihr Mitarbeiterportal enthalten sollte","isPartOf":{"@id":"https:\/\/www.investglass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#primaryimage"},"image":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#primaryimage"},"thumbnailUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png","datePublished":"2021-05-15T22:22:27+00:00","dateModified":"2026-06-25T11:20:01+00:00","description":"Erfahren Sie, welche Funktionen ein effektives Mitarbeiterportal haben muss, um die Kommunikation, das Engagement und die Produktivit\u00e4t in Ihrem Unternehmen zu f\u00f6rdern.","breadcrumb":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#primaryimage","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2025\/03\/InvestGlass-Automation-2024-3307a29b.png","width":2048,"height":1402,"caption":"InvestGlass Automations for collaborative portal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"InvestGlass","item":"https:\/\/www.investglass.com\/"},{"@type":"ListItem","position":2,"name":"A Guide to What Your Employee Portal Should Include"}]},{"@type":"WebSite","@id":"https:\/\/www.investglass.com\/#website","url":"https:\/\/www.investglass.com\/","name":"InvestGlass","description":"Das Swiss Sovereign CRM","publisher":{"@id":"https:\/\/www.investglass.com\/#organization"},"alternateName":"InvestGlass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investglass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/www.investglass.com\/#organization","name":"InvestGlass","url":"https:\/\/www.investglass.com\/","logo":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/investglass","https:\/\/www.linkedin.com\/company\/investglass\/","https:\/\/www.youtube.com\/channel\/UCt5r5XgzbSq2KhguJQxCwyA"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.investglass.com\/#\/schema\/person\/4682ebae5d718a2ed1b77c9dab0a1f24","name":"InvestGlass","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fb928ff37ca45def17ac75d6e799fb75f3f24f123aa31be169bfaf65f59dd40?s=96&d=mm&r=g","caption":"InvestGlass"},"sameAs":["https:\/\/www.investglass.com"],"url":"https:\/\/www.investglass.com\/de\/author\/axginvestglass-com\/"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.investglass.com\/a-guide-to-what-your-employee-portal-should-include-words\/#local-main-organization-logo","url":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","contentUrl":"https:\/\/www.investglass.com\/wp-content\/uploads\/2023\/10\/InvestGlass-blue2.png","width":839,"height":192,"caption":"InvestGlass"}]}},"_links":{"self":[{"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/posts\/28957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/comments?post=28957"}],"version-history":[{"count":0,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/posts\/28957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/media\/45510"}],"wp:attachment":[{"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/media?parent=28957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/categories?post=28957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investglass.com\/de\/wp-json\/wp\/v2\/tags?post=28957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}